{"id":1684,"date":"2025-04-23T11:38:58","date_gmt":"2025-04-23T11:38:58","guid":{"rendered":"https:\/\/www.telaled.com\/?page_id=1684"},"modified":"2025-07-15T11:42:14","modified_gmt":"2025-07-15T11:42:14","slug":"home","status":"publish","type":"page","link":"https:\/\/www.telaled.com\/tr\/","title":{"rendered":"EV"},"content":{"rendered":"<div class=\"banner has-hover has-video\" id=\"banner-1324367334\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <div class=\"bg fill bg-fill\"><\/div>\n            \t<div class=\"video-overlay no-click fill hide-for-medium\"><\/div>\n\t<video class=\"video-bg fill hide-for-medium\" preload playsinline autoplay muted loop>\n\t\t<source src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/fabrica-painel-de-led.mp4\" type=\"video\/mp4\">\t<\/video>\n            <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n   <div id=\"text-box-1710860530\" class=\"text-box banner-layer x50 md-x50 lg-x0 y95 md-y50 lg-y50 res-text\">\n                     <div data-animate=\"none\">           <div class=\"text-box-content text\">\n              \n              <div class=\"text-inner text-left\">\n                  \n\n\t<div id=\"text-805616068\" class=\"text hide-for-medium\">\n\t\t\n\n<h1><span style=\"font-size: 50%;\">Dijital G\u00f6rselle\u015ftirme \u00c7\u00f6z\u00fcmleri Uzman\u0131:<\/span><br \/><span style=\"font-size: 50%;\">Reklam ama\u00e7l\u0131 LED panellerden ticari LCD ekranlara kadar<\/span><\/h1>\n\t\t\n<style>\n#text-805616068 {\n  font-size: 0.9rem;\n  line-height: 1;\n  color: rgb(247, 236, 236);\n}\n#text-805616068 > * {\n  color: rgb(247, 236, 236);\n}\n@media (min-width:550px) {\n  #text-805616068 {\n    font-size: 1.65rem;\n    line-height: 1;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-1561622494\" class=\"text show-for-small\">\n\t\t\n\n<h1><span style=\"font-size: 28%;\">Dijital G\u00f6rselle\u015ftirme \u00c7\u00f6z\u00fcmleri Uzman\u0131:<\/span><br \/><span style=\"font-size: 28%;\">Reklam ama\u00e7l\u0131 LED panellerden ticari LCD ekranlara kadar<\/span><\/h1>\n\t\t\n<style>\n#text-1561622494 {\n  font-size: 0.95rem;\n  line-height: 1;\n  color: rgb(247, 236, 236);\n}\n#text-1561622494 > * {\n  color: rgb(247, 236, 236);\n}\n@media (min-width:550px) {\n  #text-1561622494 {\n    font-size: 1.65rem;\n    line-height: 1;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row row-large align-middle\"  id=\"row-1880073331\">\n\n\n\t<div id=\"col-1836783424\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<a href=\"#contact-form\" target=\"_blank\" class=\"button primary is-gradient is-small box-shadow-1 expand\" rel=\"noopener\"  style=\"border-radius:99px;\">\n    <span>Bize Ula\u015f\u0131n<\/span>\n  <\/a>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\n<style>\n#row-1880073331 > .col > .col-inner {\n  padding: 10px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #row-1880073331 > .col > .col-inner {\n    padding: 50px 0px 0px 0px;\n  }\n}\n<\/style>\n<\/div>\n\t<div id=\"text-4177596128\" class=\"text\">\n\t\t\n\n\t<div id=\"contact-form\"\n\t     class=\"lightbox-by-id lightbox-content mfp-hide lightbox-white\"\n\t     style=\"max-width:800px ;padding:30px\">\n\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f5-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"5\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"\u0130leti\u015fim formu\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o1\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"5\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f5-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class='custom_contact_style'>\n\t<p><label> Ad\u0131n\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-nome\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"name\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"seu-nome\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> E-postan\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"seu-email\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> Mesaj\u0131n\u0131z (iste\u011fe ba\u011fl\u0131)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"sua-mensagem\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"sua-mensagem\"><\/textarea><\/span> <\/label>\n\t<\/p>\n\t<div style=\"margin-bottom:10px;\">\n\t\t<p><span class=\"wpcf7-form-control-wrap kc_captcha cf7ic-toggle\" data-name=\"kc_captcha\"><span class=\"wpcf7-form-control wpcf7-radio\"><span class=\"captcha-image\" style=\"display: none;\"><span class=\"cf7ic_instructions\">L\u00fctfen se\u00e7erek insan oldu\u011funuzu kan\u0131tlay\u0131n.<span> bardak<\/span>.<\/span><label><input aria-label=\"1\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 576 512\"><path fill=\"currentColor\" d=\"M259 18l-65 132-146 22c-26 3-37 36-18 54l106 103-25 146c-5 26 23 46 46 33l131-68 131 68c23 13 51-7 46-33l-25-146 106-103c19-18 8-51-18-54l-146-22-65-132a32 32 0 00-58 0z\"\/><\/svg><\/label><label><input aria-label=\"2\" type=\"radio\" name=\"kc_captcha\" value=\"kc_human\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 640 512\"><path fill=\"currentColor\" d=\"M192 384h192c53 0 96-43 96-96h32a128 128 0 000-256H120c-13 0-24 11-24 24v232c0 53 43 96 96 96zM512 96a64 64 0 010 128h-32V96h32zm48 384H48c-47 0-61-64-36-64h584c25 0 11 64-36 64z\"\/><\/svg><\/label><label><input aria-label=\"3\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 384 512\"><path fill=\"currentColor\" d=\"M377 375l-83-87h34c21 0 32-25 17-40l-82-88h33c21 0 32-25 18-40L210 8c-10-11-26-11-36 0L70 120c-14 15-3 40 18 40h33l-82 88c-15 15-4 40 17 40h34L7 375c-15 16-4 41 17 41h120c0 33-11 49-34 68-12 9-5 28 10 28h144c15 0 22-19 10-28-20-16-34-32-34-68h120c21 0 32-25 17-41z\"\/><\/svg><\/label>\r\n    <\/span>\r\n    <span style=\"display:none\">\r\n        <input type=\"text\" name=\"kc_honeypot\">\r\n    <\/span><\/span><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div style=\"width:100%;\">\n\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner full-width\" type=\"submit\" value=\"G\u00f6ndermek i\u00e7in\" \/>\n\t\t<\/p>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"tr\"\/><\/form>\n<\/div>\n\t<\/div>\n\t\n\t\n\t\t\n<style>\n#text-4177596128 {\n  color: rgb(247, 236, 236);\n}\n#text-4177596128 > * {\n  color: rgb(247, 236, 236);\n}\n<\/style>\n\t<\/div>\n\t\n\n              <\/div>\n           <\/div>\n       <\/div>                     \n<style>\n#text-box-1710860530 .text-inner {\n  padding: 10px 10px 10px 10px;\n}\n#text-box-1710860530 {\n  width: 100%;\n}\n#text-box-1710860530 .text-box-content {\n  font-size: 130%;\n}\n@media (min-width:550px) {\n  #text-box-1710860530 {\n    width: 95%;\n  }\n  #text-box-1710860530 .text-box-content {\n    font-size: 130%;\n  }\n}\n@media (min-width:850px) {\n  #text-box-1710860530 {\n    width: 100%;\n  }\n}\n<\/style>\n    <\/div>\n \n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1324367334 {\n  padding-top: 72%;\n}\n#banner-1324367334 .bg.bg-loaded {\n  background-image: url(https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/fundo-042319.webp);\n}\n#banner-1324367334 .overlay {\n  background-color: rgba(0, 0, 0, 0.733);\n}\n#banner-1324367334 .bg {\n  background-position: 55% 59%;\n}\n@media (min-width:550px) {\n  #banner-1324367334 {\n    padding-top: 45%;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\t<section class=\"section\" id=\"section_1896697379\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-width:1px 0px 1px 0px;\">\n\t<\/div>\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row align-middle\"  id=\"row-1088049437\">\n\n\n\t<div id=\"col-1728497069\" class=\"col medium-12 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1492017971\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-zoom image-cover dark\" style=\"padding-top:75%;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"590\" height=\"465\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/Fabrica_1.webp\" class=\"attachment-original size-original\" alt=\"Fabrika\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/Fabrica_1.webp 590w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/Fabrica_1-300x236.webp 300w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/Fabrica_1-15x12.webp 15w\" sizes=\"auto, (max-width: 590px) 100vw, 590px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1492017971 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1822163078\" class=\"col medium-12 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-4124313238\" class=\"text\">\n\t\t\n\n<h2><span style=\"font-size: 100%;\"><strong>TELALED: Brezilya i\u00e7in Eksiksiz LED ve LCD \u00c7\u00f6z\u00fcm\u00fcn\u00fcz<\/strong><\/span><\/h2>\n\t\t\n<style>\n#text-4124313238 {\n  font-size: 1rem;\n  line-height: 1.5;\n}\n@media (min-width:850px) {\n  #text-4124313238 {\n    font-size: 1.2rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row\"  id=\"row-1245241274\">\n\n\n\t<div id=\"col-285698495\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<p>TELALED, 20 y\u0131ll\u0131k k\u00fcresel deneyimiyle al\u0131\u015fveri\u015f merkezleri, stadyumlar, i\u015fletmeler ve kamusal alanlar gibi \u00e7e\u015fitli ortamlara y\u00f6nelik y\u00fcksek performansl\u0131 LED ve LCD ekranlar konusunda uzmanla\u015fm\u0131\u015ft\u0131r. \u00dcr\u00fcnlerimiz 72 saatlik d\u00f6ng\u00fclerle titiz m\u00fchendislik testlerinden ge\u00e7irilmekte ve 3 y\u0131l garanti ile sunularak ola\u011fan\u00fcst\u00fc dayan\u0131kl\u0131l\u0131k ve parlakl\u0131k sa\u011flanmaktad\u0131r.<\/p>\n<p>Kurulumdan bak\u0131ma kadar her konuda sertifikal\u0131 m\u00fchendislerimizle 7\/24 uzaktan teknik destek sunuyoruz. Her \u00f6l\u00e7ekteki projeyi kapsayan, en son teknolojiyi rakipsiz maliyet etkinli\u011fiyle birle\u015ftiren \u00f6zelle\u015ftirilmi\u015f \u00e7\u00f6z\u00fcmler geli\u015ftiriyoruz.<\/p>\n<p>\u0130\u015fletmenizi g\u00fcvenle ve \u00e7evresel sorumluluk bilinciyle d\u00f6n\u00fc\u015ft\u00fcren yenilikler i\u00e7in TELALED&#039;i se\u00e7in.<\/p>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-285698495 > .col-inner {\n  padding: 0px 0px 0px 0px;\n  margin: 0px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1822163078 > .col-inner {\n  margin: -30px 0px -60px 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1896697379 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n@media (min-width:850px) {\n  #section_1896697379 {\n    padding-top: 80px;\n    padding-bottom: 80px;\n  }\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section\" id=\"section_658693940\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-366966432\">\n\n\n\t<div id=\"col-1252356925\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-3675487879\" class=\"text\">\n\t\t\n\n<h2>Her T\u00fcrl\u00fc Uygulama \u0130\u00e7in LED Panel \u00c7e\u015fitleri<\/h2>\n\t\t\n<style>\n#text-3675487879 {\n  font-size: 1rem;\n  text-align: center;\n}\n@media (min-width:850px) {\n  #text-3675487879 {\n    font-size: 1.3rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-1985036081\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1985036081 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<div class=\"row align-equal\"  id=\"row-1170087939\">\n\n\n\t<div id=\"col-1048484584\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner box-shadow-1\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-zoom\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"380\" height=\"325\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/painel-de-led-indoor.webp\" class=\"attachment-original size-original\" alt=\"i\u00e7 mekan LED paneli\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/painel-de-led-indoor.webp 380w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/painel-de-led-indoor-300x257.webp 300w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/painel-de-led-indoor-14x12.webp 14w\" sizes=\"auto, (max-width: 380px) 100vw, 380px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n<h3>\u0130\u00e7 Mekan LED Paneli<\/h3>\n<p>Parlak HD ekran, d\u00fc\u015f\u00fck g\u00fc\u00e7 t\u00fcketimi ve i\u00e7 mekanlar i\u00e7in \u00e7ok y\u00f6nl\u00fc kurulum imkan\u0131.<\/p>\n<a href=\"#contact-form\" class=\"button primary is-outline\"  style=\"border-radius:99px;\">\n    <span>\u00dccretsiz fiyat teklifi<\/span>\n  <\/a>\n\n\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"contact-form\"\n\t     class=\"lightbox-by-id lightbox-content mfp-hide lightbox-white\"\n\t     style=\"max-width:800px ;padding:30px\">\n\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f5-o2\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"5\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o2\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"\u0130leti\u015fim formu\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o2\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"5\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f5-o2\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class='custom_contact_style'>\n\t<p><label> Ad\u0131n\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-nome\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"name\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"seu-nome\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> E-postan\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"seu-email\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> Mesaj\u0131n\u0131z (iste\u011fe ba\u011fl\u0131)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"sua-mensagem\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"sua-mensagem\"><\/textarea><\/span> <\/label>\n\t<\/p>\n\t<div style=\"margin-bottom:10px;\">\n\t\t<p><span class=\"wpcf7-form-control-wrap kc_captcha cf7ic-toggle\" data-name=\"kc_captcha\"><span class=\"wpcf7-form-control wpcf7-radio\"><span class=\"captcha-image\" style=\"display: none;\"><span class=\"cf7ic_instructions\">L\u00fctfen se\u00e7erek insan oldu\u011funuzu kan\u0131tlay\u0131n.<span> ev<\/span>.<\/span><label><input aria-label=\"1\" type=\"radio\" name=\"kc_captcha\" value=\"kc_human\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 576 512\"><path fill=\"currentColor\" d=\"M488 313v143c0 13-11 24-24 24H348c-7 0-12-5-12-12V356c0-7-5-12-12-12h-72c-7 0-12 5-12 12v112c0 7-5 12-12 12H112c-13 0-24-11-24-24V313c0-4 2-7 4-10l188-154c5-4 11-4 16 0l188 154c2 3 4 6 4 10zm84-61l-84-69V44c0-6-5-12-12-12h-56c-7 0-12 6-12 12v73l-89-74a48 48 0 00-61 0L4 252c-5 4-5 12-1 17l25 31c5 5 12 5 17 1l235-193c5-4 11-4 16 0l235 193c5 5 13 4 17-1l25-31c4-6 4-13-1-17z\"\/><\/svg><\/label><label><input aria-label=\"2\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path fill=\"currentColor\" d=\"M500 168h-55l-8-21a127 127 0 00-120-83H195a127 127 0 00-120 83l-8 21H12c-8 0-14 8-11 16l8 24a12 12 0 0011 8h29a64 64 0 00-33 56v48c0 16 6 31 16 42v62c0 13 11 24 24 24h48c13 0 24-11 24-24v-40h256v40c0 13 11 24 24 24h48c13 0 24-11 24-24v-62c10-11 16-26 16-42v-48c0-24-13-45-33-56h29a12 12 0 0011-8l8-24c3-8-3-16-11-16zm-365 2c9-25 33-42 60-42h122c27 0 51 17 60 42l15 38H120l15-38zM88 328a32 32 0 010-64c18 0 48 30 48 48s-30 16-48 16zm336 0c-18 0-48 2-48-16s30-48 48-48 32 14 32 32-14 32-32 32z\"\/><\/svg><\/label><label><input aria-label=\"3\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 576 512\"><path fill=\"currentColor\" d=\"M472 200H360L256 6a12 12 0 00-10-6h-58c-8 0-14 7-12 15l34 185H100l-35-58a12 12 0 00-10-6H12c-8 0-13 7-12 14l21 106L0 362c-1 7 4 14 12 14h43c4 0 8-2 10-6l35-58h110l-34 185c-2 8 4 15 12 15h58a12 12 0 0010-6l104-194h112c57 0 104-25 104-56s-47-56-104-56z\"\/><\/svg><\/label>\r\n    <\/span>\r\n    <span style=\"display:none\">\r\n        <input type=\"text\" name=\"kc_honeypot\">\r\n    <\/span><\/span><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div style=\"width:100%;\">\n\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner full-width\" type=\"submit\" value=\"G\u00f6ndermek i\u00e7in\" \/>\n\t\t<\/p>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"tr\"\/><\/form>\n<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1048484584 > .col-inner {\n  border-radius: 8px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-472312549\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner box-shadow-1\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-zoom\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"380\" height=\"325\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/painel-de-led-outdoor.webp\" class=\"attachment-original size-original\" alt=\"d\u0131\u015f mekan LED paneli\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/painel-de-led-outdoor.webp 380w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/painel-de-led-outdoor-300x257.webp 300w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/painel-de-led-outdoor-14x12.webp 14w\" sizes=\"auto, (max-width: 380px) 100vw, 380px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n<h3>D\u0131\u015f Mekan LED Paneli<\/h3>\n<p>Y\u00fcksek parlakl\u0131k, su ge\u00e7irmezlik, h\u0131zl\u0131 kurulum ve parlak g\u00fcne\u015f \u0131\u015f\u0131\u011f\u0131nda bile net g\u00f6r\u00fcnt\u00fc!<\/p>\n<a href=\"#contact-form\" class=\"button primary is-outline\"  style=\"border-radius:99px;\">\n    <span>\u00dccretsiz fiyat teklifi<\/span>\n  <\/a>\n\n\n\t<div id=\"contact-form\"\n\t     class=\"lightbox-by-id lightbox-content mfp-hide lightbox-white\"\n\t     style=\"max-width:800px ;padding:30px\">\n\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f5-o3\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"5\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o3\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"\u0130leti\u015fim formu\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o3\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"5\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f5-o3\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class='custom_contact_style'>\n\t<p><label> Ad\u0131n\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-nome\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"name\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"seu-nome\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> E-postan\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"seu-email\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> Mesaj\u0131n\u0131z (iste\u011fe ba\u011fl\u0131)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"sua-mensagem\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"sua-mensagem\"><\/textarea><\/span> <\/label>\n\t<\/p>\n\t<div style=\"margin-bottom:10px;\">\n\t\t<p><span class=\"wpcf7-form-control-wrap kc_captcha cf7ic-toggle\" data-name=\"kc_captcha\"><span class=\"wpcf7-form-control wpcf7-radio\"><span class=\"captcha-image\" style=\"display: none;\"><span class=\"cf7ic_instructions\">L\u00fctfen se\u00e7erek insan oldu\u011funuzu kan\u0131tlay\u0131n.<span> y\u0131ld\u0131z<\/span>.<\/span><label><input aria-label=\"1\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 576 512\"><path fill=\"currentColor\" d=\"M488 313v143c0 13-11 24-24 24H348c-7 0-12-5-12-12V356c0-7-5-12-12-12h-72c-7 0-12 5-12 12v112c0 7-5 12-12 12H112c-13 0-24-11-24-24V313c0-4 2-7 4-10l188-154c5-4 11-4 16 0l188 154c2 3 4 6 4 10zm84-61l-84-69V44c0-6-5-12-12-12h-56c-7 0-12 6-12 12v73l-89-74a48 48 0 00-61 0L4 252c-5 4-5 12-1 17l25 31c5 5 12 5 17 1l235-193c5-4 11-4 16 0l235 193c5 5 13 4 17-1l25-31c4-6 4-13-1-17z\"\/><\/svg><\/label><label><input aria-label=\"2\" type=\"radio\" name=\"kc_captcha\" value=\"kc_human\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 576 512\"><path fill=\"currentColor\" d=\"M259 18l-65 132-146 22c-26 3-37 36-18 54l106 103-25 146c-5 26 23 46 46 33l131-68 131 68c23 13 51-7 46-33l-25-146 106-103c19-18 8-51-18-54l-146-22-65-132a32 32 0 00-58 0z\"\/><\/svg><\/label><label><input aria-label=\"3\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 640 512\"><path fill=\"currentColor\" d=\"M192 384h192c53 0 96-43 96-96h32a128 128 0 000-256H120c-13 0-24 11-24 24v232c0 53 43 96 96 96zM512 96a64 64 0 010 128h-32V96h32zm48 384H48c-47 0-61-64-36-64h584c25 0 11 64-36 64z\"\/><\/svg><\/label>\r\n    <\/span>\r\n    <span style=\"display:none\">\r\n        <input type=\"text\" name=\"kc_honeypot\">\r\n    <\/span><\/span><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div style=\"width:100%;\">\n\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner full-width\" type=\"submit\" value=\"G\u00f6ndermek i\u00e7in\" \/>\n\t\t<\/p>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"tr\"\/><\/form>\n<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-472312549 > .col-inner {\n  border-radius: 8px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-2065887\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner box-shadow-1\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-zoom\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"380\" height=\"325\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/placa-de-led-para-propaganda.webp\" class=\"attachment-original size-original\" alt=\"LED reklam panosu\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/placa-de-led-para-propaganda.webp 380w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/placa-de-led-para-propaganda-300x257.webp 300w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/placa-de-led-para-propaganda-14x12.webp 14w\" sizes=\"auto, (max-width: 380px) 100vw, 380px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n<h3>LED Reklam Paneli<\/h3>\n<p>G\u00fcnd\u00fcz\/gece g\u00f6r\u00fcn\u00fcrl\u00fc\u011f\u00fc, canl\u0131 renkler ve uzaktan g\u00fcncellemeler dikkat \u00e7ekiyor.<\/p>\n<a href=\"#contact-form\" class=\"button primary is-outline\"  style=\"border-radius:99px;\">\n    <span>\u00dccretsiz fiyat teklifi<\/span>\n  <\/a>\n\n\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"contact-form\"\n\t     class=\"lightbox-by-id lightbox-content mfp-hide lightbox-white\"\n\t     style=\"max-width:800px ;padding:30px\">\n\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f5-o4\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"5\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o4\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"\u0130leti\u015fim formu\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o4\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"5\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f5-o4\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class='custom_contact_style'>\n\t<p><label> Ad\u0131n\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-nome\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"name\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"seu-nome\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> E-postan\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"seu-email\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> Mesaj\u0131n\u0131z (iste\u011fe ba\u011fl\u0131)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"sua-mensagem\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"sua-mensagem\"><\/textarea><\/span> <\/label>\n\t<\/p>\n\t<div style=\"margin-bottom:10px;\">\n\t\t<p><span class=\"wpcf7-form-control-wrap kc_captcha cf7ic-toggle\" data-name=\"kc_captcha\"><span class=\"wpcf7-form-control wpcf7-radio\"><span class=\"captcha-image\" style=\"display: none;\"><span class=\"cf7ic_instructions\">L\u00fctfen se\u00e7erek insan oldu\u011funuzu kan\u0131tlay\u0131n.<span> y\u0131ld\u0131z<\/span>.<\/span><label><input aria-label=\"1\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 576 512\"><path fill=\"currentColor\" d=\"M488 313v143c0 13-11 24-24 24H348c-7 0-12-5-12-12V356c0-7-5-12-12-12h-72c-7 0-12 5-12 12v112c0 7-5 12-12 12H112c-13 0-24-11-24-24V313c0-4 2-7 4-10l188-154c5-4 11-4 16 0l188 154c2 3 4 6 4 10zm84-61l-84-69V44c0-6-5-12-12-12h-56c-7 0-12 6-12 12v73l-89-74a48 48 0 00-61 0L4 252c-5 4-5 12-1 17l25 31c5 5 12 5 17 1l235-193c5-4 11-4 16 0l235 193c5 5 13 4 17-1l25-31c4-6 4-13-1-17z\"\/><\/svg><\/label><label><input aria-label=\"2\" type=\"radio\" name=\"kc_captcha\" value=\"kc_human\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 576 512\"><path fill=\"currentColor\" d=\"M259 18l-65 132-146 22c-26 3-37 36-18 54l106 103-25 146c-5 26 23 46 46 33l131-68 131 68c23 13 51-7 46-33l-25-146 106-103c19-18 8-51-18-54l-146-22-65-132a32 32 0 00-58 0z\"\/><\/svg><\/label><label><input aria-label=\"3\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path fill=\"currentColor\" d=\"M350 99c-54 0-98-35-166-35-25 0-47 4-68 12a56 56 0 004-24C118 24 95 1 66 0a56 56 0 00-34 102v386c0 13 11 24 24 24h16c13 0 24-11 24-24v-94c28-12 64-23 114-23 54 0 98 35 166 35 48 0 86-16 122-41 9-6 14-15 14-26V96c0-23-24-39-45-29-35 16-77 32-117 32z\"\/><\/svg><\/label>\r\n    <\/span>\r\n    <span style=\"display:none\">\r\n        <input type=\"text\" name=\"kc_honeypot\">\r\n    <\/span><\/span><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div style=\"width:100%;\">\n\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner full-width\" type=\"submit\" value=\"G\u00f6ndermek i\u00e7in\" \/>\n\t\t<\/p>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"tr\"\/><\/form>\n<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-2065887 > .col-inner {\n  border-radius: 8px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1252356925 > .col-inner {\n  padding: 30px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-676985538\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"row align-equal\"  id=\"row-885393917\">\n\n\n\t<div id=\"col-1926446141\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner box-shadow-1\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-zoom\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"380\" height=\"325\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/painel-de-led-para-alugar_.webp\" class=\"attachment-original size-original\" alt=\"Kiral\u0131k LED panel\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/painel-de-led-para-alugar_.webp 380w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/painel-de-led-para-alugar_-300x257.webp 300w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/painel-de-led-para-alugar_-14x12.webp 14w\" sizes=\"auto, (max-width: 380px) 100vw, 380px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n<h3>Kiral\u0131k LED Panel<\/h3>\n<p>Etkinlikler i\u00e7in hafif mod\u00fcller: h\u0131zl\u0131 kurulum, y\u00fcksek \u00e7\u00f6z\u00fcn\u00fcrl\u00fck ve ayarlanabilir parlakl\u0131k.<\/p>\n<a href=\"#contact-form\" class=\"button primary is-outline\"  style=\"border-radius:99px;\">\n    <span>\u00dccretsiz fiyat teklifi<\/span>\n  <\/a>\n\n\n\t<div id=\"contact-form\"\n\t     class=\"lightbox-by-id lightbox-content mfp-hide lightbox-white\"\n\t     style=\"max-width:800px ;padding:30px\">\n\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f5-o5\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"5\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o5\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"\u0130leti\u015fim formu\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o5\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"5\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f5-o5\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class='custom_contact_style'>\n\t<p><label> Ad\u0131n\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-nome\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"name\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"seu-nome\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> E-postan\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"seu-email\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> Mesaj\u0131n\u0131z (iste\u011fe ba\u011fl\u0131)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"sua-mensagem\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"sua-mensagem\"><\/textarea><\/span> <\/label>\n\t<\/p>\n\t<div style=\"margin-bottom:10px;\">\n\t\t<p><span class=\"wpcf7-form-control-wrap kc_captcha cf7ic-toggle\" data-name=\"kc_captcha\"><span class=\"wpcf7-form-control wpcf7-radio\"><span class=\"captcha-image\" style=\"display: none;\"><span class=\"cf7ic_instructions\">L\u00fctfen se\u00e7erek insan oldu\u011funuzu kan\u0131tlay\u0131n.<span> bayrak<\/span>.<\/span><label><input aria-label=\"1\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 576 512\"><path fill=\"currentColor\" d=\"M488 313v143c0 13-11 24-24 24H348c-7 0-12-5-12-12V356c0-7-5-12-12-12h-72c-7 0-12 5-12 12v112c0 7-5 12-12 12H112c-13 0-24-11-24-24V313c0-4 2-7 4-10l188-154c5-4 11-4 16 0l188 154c2 3 4 6 4 10zm84-61l-84-69V44c0-6-5-12-12-12h-56c-7 0-12 6-12 12v73l-89-74a48 48 0 00-61 0L4 252c-5 4-5 12-1 17l25 31c5 5 12 5 17 1l235-193c5-4 11-4 16 0l235 193c5 5 13 4 17-1l25-31c4-6 4-13-1-17z\"\/><\/svg><\/label><label><input aria-label=\"2\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 640 512\"><path fill=\"currentColor\" d=\"M192 384h192c53 0 96-43 96-96h32a128 128 0 000-256H120c-13 0-24 11-24 24v232c0 53 43 96 96 96zM512 96a64 64 0 010 128h-32V96h32zm48 384H48c-47 0-61-64-36-64h584c25 0 11 64-36 64z\"\/><\/svg><\/label><label><input aria-label=\"3\" type=\"radio\" name=\"kc_captcha\" value=\"kc_human\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path fill=\"currentColor\" d=\"M350 99c-54 0-98-35-166-35-25 0-47 4-68 12a56 56 0 004-24C118 24 95 1 66 0a56 56 0 00-34 102v386c0 13 11 24 24 24h16c13 0 24-11 24-24v-94c28-12 64-23 114-23 54 0 98 35 166 35 48 0 86-16 122-41 9-6 14-15 14-26V96c0-23-24-39-45-29-35 16-77 32-117 32z\"\/><\/svg><\/label>\r\n    <\/span>\r\n    <span style=\"display:none\">\r\n        <input type=\"text\" name=\"kc_honeypot\">\r\n    <\/span><\/span><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div style=\"width:100%;\">\n\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner full-width\" type=\"submit\" value=\"G\u00f6ndermek i\u00e7in\" \/>\n\t\t<\/p>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"tr\"\/><\/form>\n<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1926446141 > .col-inner {\n  border-radius: 8px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-618536869\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner box-shadow-1\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-zoom\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"380\" height=\"325\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/piso-de-led-interativo.webp\" class=\"attachment-original size-original\" alt=\"etkile\u015fimli LED zemin\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/piso-de-led-interativo.webp 380w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/piso-de-led-interativo-300x257.webp 300w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/piso-de-led-interativo-14x12.webp 14w\" sizes=\"auto, (max-width: 380px) 100vw, 380px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n<h3>\u0130nteraktif LED Zemin<\/h3>\n<p>Ezilmeye kar\u015f\u0131 dayan\u0131kl\u0131, etkinlikler\/partiler i\u00e7in ideal: canl\u0131 renkler ve an\u0131nda etkile\u015fim.<\/p>\n<a href=\"#contact-form\" class=\"button primary is-outline\"  style=\"border-radius:99px;\">\n    <span>\u00dccretsiz fiyat teklifi<\/span>\n  <\/a>\n\n\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"contact-form\"\n\t     class=\"lightbox-by-id lightbox-content mfp-hide lightbox-white\"\n\t     style=\"max-width:800px ;padding:30px\">\n\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f5-o6\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"5\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o6\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"\u0130leti\u015fim formu\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o6\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"5\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f5-o6\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class='custom_contact_style'>\n\t<p><label> Ad\u0131n\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-nome\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"name\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"seu-nome\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> E-postan\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"seu-email\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> Mesaj\u0131n\u0131z (iste\u011fe ba\u011fl\u0131)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"sua-mensagem\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"sua-mensagem\"><\/textarea><\/span> <\/label>\n\t<\/p>\n\t<div style=\"margin-bottom:10px;\">\n\t\t<p><span class=\"wpcf7-form-control-wrap kc_captcha cf7ic-toggle\" data-name=\"kc_captcha\"><span class=\"wpcf7-form-control wpcf7-radio\"><span class=\"captcha-image\" style=\"display: none;\"><span class=\"cf7ic_instructions\">L\u00fctfen se\u00e7erek insan oldu\u011funuzu kan\u0131tlay\u0131n.<span> y\u0131ld\u0131z<\/span>.<\/span><label><input aria-label=\"1\" type=\"radio\" name=\"kc_captcha\" value=\"kc_human\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 576 512\"><path fill=\"currentColor\" d=\"M259 18l-65 132-146 22c-26 3-37 36-18 54l106 103-25 146c-5 26 23 46 46 33l131-68 131 68c23 13 51-7 46-33l-25-146 106-103c19-18 8-51-18-54l-146-22-65-132a32 32 0 00-58 0z\"\/><\/svg><\/label><label><input aria-label=\"2\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path fill=\"currentColor\" d=\"M512 176a176 176 0 01-209 173l-24 27a24 24 0 01-18 8h-37v40c0 13-11 24-24 24h-40v40c0 13-11 24-24 24H24c-13 0-24-11-24-24v-78c0-6 3-13 7-17l162-162a176 176 0 11343-55zm-176-48a48 48 0 1096 0 48 48 0 00-96 0z\"\/><\/svg><\/label><label><input aria-label=\"3\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 576 512\"><path fill=\"currentColor\" d=\"M472 200H360L256 6a12 12 0 00-10-6h-58c-8 0-14 7-12 15l34 185H100l-35-58a12 12 0 00-10-6H12c-8 0-13 7-12 14l21 106L0 362c-1 7 4 14 12 14h43c4 0 8-2 10-6l35-58h110l-34 185c-2 8 4 15 12 15h58a12 12 0 0010-6l104-194h112c57 0 104-25 104-56s-47-56-104-56z\"\/><\/svg><\/label>\r\n    <\/span>\r\n    <span style=\"display:none\">\r\n        <input type=\"text\" name=\"kc_honeypot\">\r\n    <\/span><\/span><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div style=\"width:100%;\">\n\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner full-width\" type=\"submit\" value=\"G\u00f6ndermek i\u00e7in\" \/>\n\t\t<\/p>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"tr\"\/><\/form>\n<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-618536869 > .col-inner {\n  border-radius: 8px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-158891213\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner box-shadow-1\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-zoom\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"380\" height=\"325\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/led-truck-advertising.webp\" class=\"attachment-original size-original\" alt=\"LED kamyon reklam\u0131\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/led-truck-advertising.webp 380w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/led-truck-advertising-300x257.webp 300w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/led-truck-advertising-14x12.webp 14w\" sizes=\"auto, (max-width: 380px) 100vw, 380px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n<h3>LED Kamyon Reklam\u0131<\/h3>\n<p>Sessiz jenerat\u00f6rl\u00fc ve iste\u011fe ba\u011fl\u0131 hidrolik sistemli mobil HD ekran.<\/p>\n<a href=\"#contact-form\" class=\"button primary is-outline\"  style=\"border-radius:99px;\">\n    <span>\u00dccretsiz fiyat teklifi<\/span>\n  <\/a>\n\n\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"contact-form\"\n\t     class=\"lightbox-by-id lightbox-content mfp-hide lightbox-white\"\n\t     style=\"max-width:800px ;padding:30px\">\n\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f5-o7\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"5\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o7\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"\u0130leti\u015fim formu\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o7\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"5\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f5-o7\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class='custom_contact_style'>\n\t<p><label> Ad\u0131n\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-nome\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"name\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"seu-nome\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> E-postan\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"seu-email\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> Mesaj\u0131n\u0131z (iste\u011fe ba\u011fl\u0131)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"sua-mensagem\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"sua-mensagem\"><\/textarea><\/span> <\/label>\n\t<\/p>\n\t<div style=\"margin-bottom:10px;\">\n\t\t<p><span class=\"wpcf7-form-control-wrap kc_captcha cf7ic-toggle\" data-name=\"kc_captcha\"><span class=\"wpcf7-form-control wpcf7-radio\"><span class=\"captcha-image\" style=\"display: none;\"><span class=\"cf7ic_instructions\">L\u00fctfen se\u00e7erek insan oldu\u011funuzu kan\u0131tlay\u0131n.<span> bayrak<\/span>.<\/span><label><input aria-label=\"1\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path fill=\"currentColor\" d=\"M500 168h-55l-8-21a127 127 0 00-120-83H195a127 127 0 00-120 83l-8 21H12c-8 0-14 8-11 16l8 24a12 12 0 0011 8h29a64 64 0 00-33 56v48c0 16 6 31 16 42v62c0 13 11 24 24 24h48c13 0 24-11 24-24v-40h256v40c0 13 11 24 24 24h48c13 0 24-11 24-24v-62c10-11 16-26 16-42v-48c0-24-13-45-33-56h29a12 12 0 0011-8l8-24c3-8-3-16-11-16zm-365 2c9-25 33-42 60-42h122c27 0 51 17 60 42l15 38H120l15-38zM88 328a32 32 0 010-64c18 0 48 30 48 48s-30 16-48 16zm336 0c-18 0-48 2-48-16s30-48 48-48 32 14 32 32-14 32-32 32z\"\/><\/svg><\/label><label><input aria-label=\"2\" type=\"radio\" name=\"kc_captcha\" value=\"kc_human\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path fill=\"currentColor\" d=\"M350 99c-54 0-98-35-166-35-25 0-47 4-68 12a56 56 0 004-24C118 24 95 1 66 0a56 56 0 00-34 102v386c0 13 11 24 24 24h16c13 0 24-11 24-24v-94c28-12 64-23 114-23 54 0 98 35 166 35 48 0 86-16 122-41 9-6 14-15 14-26V96c0-23-24-39-45-29-35 16-77 32-117 32z\"\/><\/svg><\/label><label><input aria-label=\"3\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path fill=\"currentColor\" d=\"M512 176a176 176 0 01-209 173l-24 27a24 24 0 01-18 8h-37v40c0 13-11 24-24 24h-40v40c0 13-11 24-24 24H24c-13 0-24-11-24-24v-78c0-6 3-13 7-17l162-162a176 176 0 11343-55zm-176-48a48 48 0 1096 0 48 48 0 00-96 0z\"\/><\/svg><\/label>\r\n    <\/span>\r\n    <span style=\"display:none\">\r\n        <input type=\"text\" name=\"kc_honeypot\">\r\n    <\/span><\/span><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div style=\"width:100%;\">\n\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner full-width\" type=\"submit\" value=\"G\u00f6ndermek i\u00e7in\" \/>\n\t\t<\/p>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"tr\"\/><\/form>\n<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-158891213 > .col-inner {\n  border-radius: 8px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-676985538 > .col-inner {\n  padding: 30px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1122041665\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"row align-equal\"  id=\"row-286644096\">\n\n\n\t<div id=\"col-1643130043\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner box-shadow-1\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-zoom\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"380\" height=\"325\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/painel-de-led-flexivel.webp\" class=\"attachment-original size-original\" alt=\"esnek LED panel\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/painel-de-led-flexivel.webp 380w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/painel-de-led-flexivel-300x257.webp 300w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/painel-de-led-flexivel-14x12.webp 14w\" sizes=\"auto, (max-width: 380px) 100vw, 380px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n<h3>Esnek LED Panel<\/h3>\n<p>145\u00b0&#039;ye kadar e\u011fim, IP65 derecesi, d\u0131\u015f mekan ortamlar\u0131 ve yarat\u0131c\u0131 projeler i\u00e7in 7000 nit parlakl\u0131k.<\/p>\n<a href=\"#contact-form\" class=\"button primary is-outline\"  style=\"border-radius:99px;\">\n    <span>\u00dccretsiz fiyat teklifi<\/span>\n  <\/a>\n\n\n\t<div id=\"contact-form\"\n\t     class=\"lightbox-by-id lightbox-content mfp-hide lightbox-white\"\n\t     style=\"max-width:800px ;padding:30px\">\n\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f5-o8\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"5\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o8\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"\u0130leti\u015fim formu\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o8\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"5\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f5-o8\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class='custom_contact_style'>\n\t<p><label> Ad\u0131n\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-nome\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"name\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"seu-nome\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> E-postan\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"seu-email\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> Mesaj\u0131n\u0131z (iste\u011fe ba\u011fl\u0131)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"sua-mensagem\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"sua-mensagem\"><\/textarea><\/span> <\/label>\n\t<\/p>\n\t<div style=\"margin-bottom:10px;\">\n\t\t<p><span class=\"wpcf7-form-control-wrap kc_captcha cf7ic-toggle\" data-name=\"kc_captcha\"><span class=\"wpcf7-form-control wpcf7-radio\"><span class=\"captcha-image\" style=\"display: none;\"><span class=\"cf7ic_instructions\">L\u00fctfen se\u00e7erek insan oldu\u011funuzu kan\u0131tlay\u0131n.<span> y\u0131ld\u0131z<\/span>.<\/span><label><input aria-label=\"1\" type=\"radio\" name=\"kc_captcha\" value=\"kc_human\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 576 512\"><path fill=\"currentColor\" d=\"M259 18l-65 132-146 22c-26 3-37 36-18 54l106 103-25 146c-5 26 23 46 46 33l131-68 131 68c23 13 51-7 46-33l-25-146 106-103c19-18 8-51-18-54l-146-22-65-132a32 32 0 00-58 0z\"\/><\/svg><\/label><label><input aria-label=\"2\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 640 512\"><path fill=\"currentColor\" d=\"M192 384h192c53 0 96-43 96-96h32a128 128 0 000-256H120c-13 0-24 11-24 24v232c0 53 43 96 96 96zM512 96a64 64 0 010 128h-32V96h32zm48 384H48c-47 0-61-64-36-64h584c25 0 11 64-36 64z\"\/><\/svg><\/label><label><input aria-label=\"3\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 576 512\"><path fill=\"currentColor\" d=\"M472 200H360L256 6a12 12 0 00-10-6h-58c-8 0-14 7-12 15l34 185H100l-35-58a12 12 0 00-10-6H12c-8 0-13 7-12 14l21 106L0 362c-1 7 4 14 12 14h43c4 0 8-2 10-6l35-58h110l-34 185c-2 8 4 15 12 15h58a12 12 0 0010-6l104-194h112c57 0 104-25 104-56s-47-56-104-56z\"\/><\/svg><\/label>\r\n    <\/span>\r\n    <span style=\"display:none\">\r\n        <input type=\"text\" name=\"kc_honeypot\">\r\n    <\/span><\/span><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div style=\"width:100%;\">\n\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner full-width\" type=\"submit\" value=\"G\u00f6ndermek i\u00e7in\" \/>\n\t\t<\/p>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"tr\"\/><\/form>\n<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1643130043 > .col-inner {\n  border-radius: 8px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1013028532\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner box-shadow-1\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-zoom\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"380\" height=\"325\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/painel-de-led-transparente.webp\" class=\"attachment-original size-original\" alt=\"\u015feffaf LED panel\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/painel-de-led-transparente.webp 380w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/painel-de-led-transparente-300x257.webp 300w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/painel-de-led-transparente-14x12.webp 14w\" sizes=\"auto, (max-width: 380px) 100vw, 380px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n<h3>\u015eeffaf LED Panel<\/h3>\n<p>90% \u015feffaf, hafif (3,5 kg\/m\u00b2), 5000 nit parlakl\u0131kta, \u00e7er\u00e7evesiz olarak vitrin ve cephelerde kullan\u0131labilen bir malzemedir.<\/p>\n<a href=\"#contact-form\" class=\"button primary is-outline\"  style=\"border-radius:99px;\">\n    <span>\u00dccretsiz fiyat teklifi<\/span>\n  <\/a>\n\n\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"contact-form\"\n\t     class=\"lightbox-by-id lightbox-content mfp-hide lightbox-white\"\n\t     style=\"max-width:800px ;padding:30px\">\n\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f5-o9\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"5\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o9\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"\u0130leti\u015fim formu\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o9\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"5\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f5-o9\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class='custom_contact_style'>\n\t<p><label> Ad\u0131n\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-nome\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"name\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"seu-nome\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> E-postan\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"seu-email\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> Mesaj\u0131n\u0131z (iste\u011fe ba\u011fl\u0131)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"sua-mensagem\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"sua-mensagem\"><\/textarea><\/span> <\/label>\n\t<\/p>\n\t<div style=\"margin-bottom:10px;\">\n\t\t<p><span class=\"wpcf7-form-control-wrap kc_captcha cf7ic-toggle\" data-name=\"kc_captcha\"><span class=\"wpcf7-form-control wpcf7-radio\"><span class=\"captcha-image\" style=\"display: none;\"><span class=\"cf7ic_instructions\">L\u00fctfen se\u00e7erek insan oldu\u011funuzu kan\u0131tlay\u0131n.<span> anahtar<\/span>.<\/span><label><input aria-label=\"1\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 576 512\"><path fill=\"currentColor\" d=\"M415 24c-53 0-103 42-127 65-24-23-74-65-127-65C70 24 16 77 16 166c0 72 67 133 69 135l187 181c9 8 23 8 32 0l187-180c2-3 69-64 69-136 0-89-54-142-145-142z\"\/><\/svg><\/label><label><input aria-label=\"2\" type=\"radio\" name=\"kc_captcha\" value=\"kc_human\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path fill=\"currentColor\" d=\"M512 176a176 176 0 01-209 173l-24 27a24 24 0 01-18 8h-37v40c0 13-11 24-24 24h-40v40c0 13-11 24-24 24H24c-13 0-24-11-24-24v-78c0-6 3-13 7-17l162-162a176 176 0 11343-55zm-176-48a48 48 0 1096 0 48 48 0 00-96 0z\"\/><\/svg><\/label><label><input aria-label=\"3\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 384 512\"><path fill=\"currentColor\" d=\"M377 375l-83-87h34c21 0 32-25 17-40l-82-88h33c21 0 32-25 18-40L210 8c-10-11-26-11-36 0L70 120c-14 15-3 40 18 40h33l-82 88c-15 15-4 40 17 40h34L7 375c-15 16-4 41 17 41h120c0 33-11 49-34 68-12 9-5 28 10 28h144c15 0 22-19 10-28-20-16-34-32-34-68h120c21 0 32-25 17-41z\"\/><\/svg><\/label>\r\n    <\/span>\r\n    <span style=\"display:none\">\r\n        <input type=\"text\" name=\"kc_honeypot\">\r\n    <\/span><\/span><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div style=\"width:100%;\">\n\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner full-width\" type=\"submit\" value=\"G\u00f6ndermek i\u00e7in\" \/>\n\t\t<\/p>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"tr\"\/><\/form>\n<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1013028532 > .col-inner {\n  border-radius: 8px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-873827879\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner box-shadow-1\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-zoom\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"380\" height=\"325\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/painel-de-led-para-taxi.webp\" class=\"attachment-original size-original\" alt=\"taksi i\u00e7in LED panel\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/painel-de-led-para-taxi.webp 380w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/painel-de-led-para-taxi-300x257.webp 300w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/painel-de-led-para-taxi-14x12.webp 14w\" sizes=\"auto, (max-width: 380px) 100vw, 380px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n<h3>Taksi i\u00e7in LED Panel<\/h3>\n<p>Dayan\u0131kl\u0131 ekran, 4500 nit parlakl\u0131k, dahili GPS, 3 y\u0131l garanti, uygulama \u00fczerinden uzaktan kumanda.<\/p>\n<a href=\"#contact-form\" class=\"button primary is-outline\"  style=\"border-radius:99px;\">\n    <span>\u00dccretsiz fiyat teklifi<\/span>\n  <\/a>\n\n\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"contact-form\"\n\t     class=\"lightbox-by-id lightbox-content mfp-hide lightbox-white\"\n\t     style=\"max-width:800px ;padding:30px\">\n\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f5-o10\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"5\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o10\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"\u0130leti\u015fim formu\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o10\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"5\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f5-o10\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class='custom_contact_style'>\n\t<p><label> Ad\u0131n\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-nome\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"name\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"seu-nome\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> E-postan\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"seu-email\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> Mesaj\u0131n\u0131z (iste\u011fe ba\u011fl\u0131)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"sua-mensagem\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"sua-mensagem\"><\/textarea><\/span> <\/label>\n\t<\/p>\n\t<div style=\"margin-bottom:10px;\">\n\t\t<p><span class=\"wpcf7-form-control-wrap kc_captcha cf7ic-toggle\" data-name=\"kc_captcha\"><span class=\"wpcf7-form-control wpcf7-radio\"><span class=\"captcha-image\" style=\"display: none;\"><span class=\"cf7ic_instructions\">L\u00fctfen se\u00e7erek insan oldu\u011funuzu kan\u0131tlay\u0131n.<span> y\u0131ld\u0131z<\/span>.<\/span><label><input aria-label=\"1\" type=\"radio\" name=\"kc_captcha\" value=\"kc_human\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 576 512\"><path fill=\"currentColor\" d=\"M259 18l-65 132-146 22c-26 3-37 36-18 54l106 103-25 146c-5 26 23 46 46 33l131-68 131 68c23 13 51-7 46-33l-25-146 106-103c19-18 8-51-18-54l-146-22-65-132a32 32 0 00-58 0z\"\/><\/svg><\/label><label><input aria-label=\"2\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path fill=\"currentColor\" d=\"M500 168h-55l-8-21a127 127 0 00-120-83H195a127 127 0 00-120 83l-8 21H12c-8 0-14 8-11 16l8 24a12 12 0 0011 8h29a64 64 0 00-33 56v48c0 16 6 31 16 42v62c0 13 11 24 24 24h48c13 0 24-11 24-24v-40h256v40c0 13 11 24 24 24h48c13 0 24-11 24-24v-62c10-11 16-26 16-42v-48c0-24-13-45-33-56h29a12 12 0 0011-8l8-24c3-8-3-16-11-16zm-365 2c9-25 33-42 60-42h122c27 0 51 17 60 42l15 38H120l15-38zM88 328a32 32 0 010-64c18 0 48 30 48 48s-30 16-48 16zm336 0c-18 0-48 2-48-16s30-48 48-48 32 14 32 32-14 32-32 32z\"\/><\/svg><\/label><label><input aria-label=\"3\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 576 512\"><path fill=\"currentColor\" d=\"M472 200H360L256 6a12 12 0 00-10-6h-58c-8 0-14 7-12 15l34 185H100l-35-58a12 12 0 00-10-6H12c-8 0-13 7-12 14l21 106L0 362c-1 7 4 14 12 14h43c4 0 8-2 10-6l35-58h110l-34 185c-2 8 4 15 12 15h58a12 12 0 0010-6l104-194h112c57 0 104-25 104-56s-47-56-104-56z\"\/><\/svg><\/label>\r\n    <\/span>\r\n    <span style=\"display:none\">\r\n        <input type=\"text\" name=\"kc_honeypot\">\r\n    <\/span><\/span><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div style=\"width:100%;\">\n\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner full-width\" type=\"submit\" value=\"G\u00f6ndermek i\u00e7in\" \/>\n\t\t<\/p>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"tr\"\/><\/form>\n<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-873827879 > .col-inner {\n  border-radius: 8px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1122041665 > .col-inner {\n  padding: 30px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-332319884\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"row align-equal\"  id=\"row-860019246\">\n\n\n\t<div id=\"col-909396710\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner box-shadow-1\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-zoom\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"380\" height=\"325\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/totem-de-led.webp\" class=\"attachment-original size-original\" alt=\"LED totem\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/totem-de-led.webp 380w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/totem-de-led-300x257.webp 300w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/totem-de-led-14x12.webp 14w\" sizes=\"auto, (max-width: 380px) 100vw, 380px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n<h3>LED Totem<\/h3>\n<p>Reklamc\u0131l\u0131k i\u00e7in dikey dijital \u00e7\u00f6z\u00fcm, kolay kurulum ve uygulama \u00fczerinden uzaktan y\u00f6netim.<\/p>\n<a href=\"#contact-form\" class=\"button primary is-outline\"  style=\"border-radius:99px;\">\n    <span>\u00dccretsiz fiyat teklifi<\/span>\n  <\/a>\n\n\n\t<div id=\"contact-form\"\n\t     class=\"lightbox-by-id lightbox-content mfp-hide lightbox-white\"\n\t     style=\"max-width:800px ;padding:30px\">\n\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f5-o11\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"5\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o11\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"\u0130leti\u015fim formu\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o11\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"5\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f5-o11\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class='custom_contact_style'>\n\t<p><label> Ad\u0131n\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-nome\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"name\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"seu-nome\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> E-postan\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"seu-email\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> Mesaj\u0131n\u0131z (iste\u011fe ba\u011fl\u0131)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"sua-mensagem\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"sua-mensagem\"><\/textarea><\/span> <\/label>\n\t<\/p>\n\t<div style=\"margin-bottom:10px;\">\n\t\t<p><span class=\"wpcf7-form-control-wrap kc_captcha cf7ic-toggle\" data-name=\"kc_captcha\"><span class=\"wpcf7-form-control wpcf7-radio\"><span class=\"captcha-image\" style=\"display: none;\"><span class=\"cf7ic_instructions\">L\u00fctfen se\u00e7erek insan oldu\u011funuzu kan\u0131tlay\u0131n.<span> bayrak<\/span>.<\/span><label><input aria-label=\"1\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 576 512\"><path fill=\"currentColor\" d=\"M488 313v143c0 13-11 24-24 24H348c-7 0-12-5-12-12V356c0-7-5-12-12-12h-72c-7 0-12 5-12 12v112c0 7-5 12-12 12H112c-13 0-24-11-24-24V313c0-4 2-7 4-10l188-154c5-4 11-4 16 0l188 154c2 3 4 6 4 10zm84-61l-84-69V44c0-6-5-12-12-12h-56c-7 0-12 6-12 12v73l-89-74a48 48 0 00-61 0L4 252c-5 4-5 12-1 17l25 31c5 5 12 5 17 1l235-193c5-4 11-4 16 0l235 193c5 5 13 4 17-1l25-31c4-6 4-13-1-17z\"\/><\/svg><\/label><label><input aria-label=\"2\" type=\"radio\" name=\"kc_captcha\" value=\"kc_human\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path fill=\"currentColor\" d=\"M350 99c-54 0-98-35-166-35-25 0-47 4-68 12a56 56 0 004-24C118 24 95 1 66 0a56 56 0 00-34 102v386c0 13 11 24 24 24h16c13 0 24-11 24-24v-94c28-12 64-23 114-23 54 0 98 35 166 35 48 0 86-16 122-41 9-6 14-15 14-26V96c0-23-24-39-45-29-35 16-77 32-117 32z\"\/><\/svg><\/label><label><input aria-label=\"3\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 640 512\"><path fill=\"currentColor\" d=\"M624 352h-16V244c0-13-5-25-14-34L494 110c-9-9-21-14-34-14h-44V48c0-26-21-48-48-48H48C22 0 0 22 0 48v320c0 27 22 48 48 48h16a96 96 0 00192 0h128a96 96 0 00192 0h48c9 0 16-7 16-16v-32c0-9-7-16-16-16zM160 464a48 48 0 110-96 48 48 0 010 96zm320 0a48 48 0 110-96 48 48 0 010 96zm80-208H416V144h44l100 100v12z\"\/><\/svg><\/label>\r\n    <\/span>\r\n    <span style=\"display:none\">\r\n        <input type=\"text\" name=\"kc_honeypot\">\r\n    <\/span><\/span><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div style=\"width:100%;\">\n\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner full-width\" type=\"submit\" value=\"G\u00f6ndermek i\u00e7in\" \/>\n\t\t<\/p>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"tr\"\/><\/form>\n<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-909396710 > .col-inner {\n  border-radius: 8px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-392997073\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner box-shadow-1\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-zoom\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"380\" height=\"325\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/painel-de-led-supermercado.webp\" class=\"attachment-original size-original\" alt=\"s\u00fcpermarket LED paneli\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/painel-de-led-supermercado.webp 380w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/painel-de-led-supermercado-300x257.webp 300w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/painel-de-led-supermercado-14x12.webp 14w\" sizes=\"auto, (max-width: 380px) 100vw, 380px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n<h3>S\u00fcpermarketler i\u00e7in LED Panel<\/h3>\n<p>Perakende raf sistemleri i\u00e7in etkile\u015fimli \u00e7\u00f6z\u00fcm, kolay kurulum ve uygulama \u00fczerinden uzaktan kontrol.<\/p>\n<a href=\"#contact-form\" class=\"button primary is-outline\"  style=\"border-radius:99px;\">\n    <span>\u00dccretsiz fiyat teklifi<\/span>\n  <\/a>\n\n\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"contact-form\"\n\t     class=\"lightbox-by-id lightbox-content mfp-hide lightbox-white\"\n\t     style=\"max-width:800px ;padding:30px\">\n\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f5-o12\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"5\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o12\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"\u0130leti\u015fim formu\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o12\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"5\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f5-o12\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class='custom_contact_style'>\n\t<p><label> Ad\u0131n\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-nome\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"name\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"seu-nome\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> E-postan\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"seu-email\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> Mesaj\u0131n\u0131z (iste\u011fe ba\u011fl\u0131)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"sua-mensagem\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"sua-mensagem\"><\/textarea><\/span> <\/label>\n\t<\/p>\n\t<div style=\"margin-bottom:10px;\">\n\t\t<p><span class=\"wpcf7-form-control-wrap kc_captcha cf7ic-toggle\" data-name=\"kc_captcha\"><span class=\"wpcf7-form-control wpcf7-radio\"><span class=\"captcha-image\" style=\"display: none;\"><span class=\"cf7ic_instructions\">L\u00fctfen se\u00e7erek insan oldu\u011funuzu kan\u0131tlay\u0131n.<span> u\u00e7ak<\/span>.<\/span><label><input aria-label=\"1\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 576 512\"><path fill=\"currentColor\" d=\"M259 18l-65 132-146 22c-26 3-37 36-18 54l106 103-25 146c-5 26 23 46 46 33l131-68 131 68c23 13 51-7 46-33l-25-146 106-103c19-18 8-51-18-54l-146-22-65-132a32 32 0 00-58 0z\"\/><\/svg><\/label><label><input aria-label=\"2\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 640 512\"><path fill=\"currentColor\" d=\"M192 384h192c53 0 96-43 96-96h32a128 128 0 000-256H120c-13 0-24 11-24 24v232c0 53 43 96 96 96zM512 96a64 64 0 010 128h-32V96h32zm48 384H48c-47 0-61-64-36-64h584c25 0 11 64-36 64z\"\/><\/svg><\/label><label><input aria-label=\"3\" type=\"radio\" name=\"kc_captcha\" value=\"kc_human\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 576 512\"><path fill=\"currentColor\" d=\"M472 200H360L256 6a12 12 0 00-10-6h-58c-8 0-14 7-12 15l34 185H100l-35-58a12 12 0 00-10-6H12c-8 0-13 7-12 14l21 106L0 362c-1 7 4 14 12 14h43c4 0 8-2 10-6l35-58h110l-34 185c-2 8 4 15 12 15h58a12 12 0 0010-6l104-194h112c57 0 104-25 104-56s-47-56-104-56z\"\/><\/svg><\/label>\r\n    <\/span>\r\n    <span style=\"display:none\">\r\n        <input type=\"text\" name=\"kc_honeypot\">\r\n    <\/span><\/span><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div style=\"width:100%;\">\n\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner full-width\" type=\"submit\" value=\"G\u00f6ndermek i\u00e7in\" \/>\n\t\t<\/p>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"tr\"\/><\/form>\n<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-392997073 > .col-inner {\n  border-radius: 8px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1278836747\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner box-shadow-1\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-zoom\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"380\" height=\"325\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/display-led-para-poste.webp\" class=\"attachment-original size-original\" alt=\"Direk i\u00e7in LED ekran\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/display-led-para-poste.webp 380w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/display-led-para-poste-300x257.webp 300w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/display-led-para-poste-14x12.webp 14w\" sizes=\"auto, (max-width: 380px) 100vw, 380px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n<h3>Direk i\u00e7in LED I\u015f\u0131k \u00c7ubu\u011fu<\/h3>\n<p>Halka a\u00e7\u0131k sokak ekran\u0131: y\u00fcksek dayan\u0131kl\u0131l\u0131k, ayarlanabilir parlakl\u0131k ve ak\u0131ll\u0131 uzaktan kumanda.<\/p>\n<a href=\"#contact-form\" class=\"button primary is-outline\"  style=\"border-radius:99px;\">\n    <span>\u00dccretsiz fiyat teklifi<\/span>\n  <\/a>\n\n\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"contact-form\"\n\t     class=\"lightbox-by-id lightbox-content mfp-hide lightbox-white\"\n\t     style=\"max-width:800px ;padding:30px\">\n\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f5-o13\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"5\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o13\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"\u0130leti\u015fim formu\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o13\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"5\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f5-o13\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class='custom_contact_style'>\n\t<p><label> Ad\u0131n\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-nome\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"name\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"seu-nome\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> E-postan\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"seu-email\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> Mesaj\u0131n\u0131z (iste\u011fe ba\u011fl\u0131)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"sua-mensagem\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"sua-mensagem\"><\/textarea><\/span> <\/label>\n\t<\/p>\n\t<div style=\"margin-bottom:10px;\">\n\t\t<p><span class=\"wpcf7-form-control-wrap kc_captcha cf7ic-toggle\" data-name=\"kc_captcha\"><span class=\"wpcf7-form-control wpcf7-radio\"><span class=\"captcha-image\" style=\"display: none;\"><span class=\"cf7ic_instructions\">L\u00fctfen se\u00e7erek insan oldu\u011funuzu kan\u0131tlay\u0131n.<span> u\u00e7ak<\/span>.<\/span><label><input aria-label=\"1\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 576 512\"><path fill=\"currentColor\" d=\"M259 18l-65 132-146 22c-26 3-37 36-18 54l106 103-25 146c-5 26 23 46 46 33l131-68 131 68c23 13 51-7 46-33l-25-146 106-103c19-18 8-51-18-54l-146-22-65-132a32 32 0 00-58 0z\"\/><\/svg><\/label><label><input aria-label=\"2\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 640 512\"><path fill=\"currentColor\" d=\"M192 384h192c53 0 96-43 96-96h32a128 128 0 000-256H120c-13 0-24 11-24 24v232c0 53 43 96 96 96zM512 96a64 64 0 010 128h-32V96h32zm48 384H48c-47 0-61-64-36-64h584c25 0 11 64-36 64z\"\/><\/svg><\/label><label><input aria-label=\"3\" type=\"radio\" name=\"kc_captcha\" value=\"kc_human\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 576 512\"><path fill=\"currentColor\" d=\"M472 200H360L256 6a12 12 0 00-10-6h-58c-8 0-14 7-12 15l34 185H100l-35-58a12 12 0 00-10-6H12c-8 0-13 7-12 14l21 106L0 362c-1 7 4 14 12 14h43c4 0 8-2 10-6l35-58h110l-34 185c-2 8 4 15 12 15h58a12 12 0 0010-6l104-194h112c57 0 104-25 104-56s-47-56-104-56z\"\/><\/svg><\/label>\r\n    <\/span>\r\n    <span style=\"display:none\">\r\n        <input type=\"text\" name=\"kc_honeypot\">\r\n    <\/span><\/span><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div style=\"width:100%;\">\n\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner full-width\" type=\"submit\" value=\"G\u00f6ndermek i\u00e7in\" \/>\n\t\t<\/p>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"tr\"\/><\/form>\n<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1278836747 > .col-inner {\n  border-radius: 8px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-332319884 > .col-inner {\n  padding: 30px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1196479078\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"row align-equal\"  id=\"row-1468797684\">\n\n\n\t<div id=\"col-72715256\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner box-shadow-1\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-zoom\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"380\" height=\"325\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/Tela-LED-para-estadio.webp\" class=\"attachment-original size-original\" alt=\"Stadyum i\u00e7in LED ekran\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/Tela-LED-para-estadio.webp 380w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/Tela-LED-para-estadio-300x257.webp 300w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/Tela-LED-para-estadio-14x12.webp 14w\" sizes=\"auto, (max-width: 380px) 100vw, 380px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n<h3>Stadyum i\u00e7in LED Ekran<\/h3>\n<p>Geni\u015f g\u00f6r\u00fc\u015f alan\u0131 ve y\u00fcksek parlakl\u0131k sunan y\u00fcksek performansl\u0131 HD spor ekran\u0131.<\/p>\n<a href=\"#contact-form\" class=\"button primary is-outline\"  style=\"border-radius:99px;\">\n    <span>\u00dccretsiz fiyat teklifi<\/span>\n  <\/a>\n\n\n\t<div id=\"contact-form\"\n\t     class=\"lightbox-by-id lightbox-content mfp-hide lightbox-white\"\n\t     style=\"max-width:800px ;padding:30px\">\n\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f5-o14\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"5\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o14\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"\u0130leti\u015fim formu\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o14\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"5\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f5-o14\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class='custom_contact_style'>\n\t<p><label> Ad\u0131n\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-nome\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"name\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"seu-nome\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> E-postan\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"seu-email\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> Mesaj\u0131n\u0131z (iste\u011fe ba\u011fl\u0131)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"sua-mensagem\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"sua-mensagem\"><\/textarea><\/span> <\/label>\n\t<\/p>\n\t<div style=\"margin-bottom:10px;\">\n\t\t<p><span class=\"wpcf7-form-control-wrap kc_captcha cf7ic-toggle\" data-name=\"kc_captcha\"><span class=\"wpcf7-form-control wpcf7-radio\"><span class=\"captcha-image\" style=\"display: none;\"><span class=\"cf7ic_instructions\">L\u00fctfen se\u00e7erek insan oldu\u011funuzu kan\u0131tlay\u0131n.<span> anahtar<\/span>.<\/span><label><input aria-label=\"1\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 576 512\"><path fill=\"currentColor\" d=\"M415 24c-53 0-103 42-127 65-24-23-74-65-127-65C70 24 16 77 16 166c0 72 67 133 69 135l187 181c9 8 23 8 32 0l187-180c2-3 69-64 69-136 0-89-54-142-145-142z\"\/><\/svg><\/label><label><input aria-label=\"2\" type=\"radio\" name=\"kc_captcha\" value=\"kc_human\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path fill=\"currentColor\" d=\"M512 176a176 176 0 01-209 173l-24 27a24 24 0 01-18 8h-37v40c0 13-11 24-24 24h-40v40c0 13-11 24-24 24H24c-13 0-24-11-24-24v-78c0-6 3-13 7-17l162-162a176 176 0 11343-55zm-176-48a48 48 0 1096 0 48 48 0 00-96 0z\"\/><\/svg><\/label><label><input aria-label=\"3\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 640 512\"><path fill=\"currentColor\" d=\"M624 352h-16V244c0-13-5-25-14-34L494 110c-9-9-21-14-34-14h-44V48c0-26-21-48-48-48H48C22 0 0 22 0 48v320c0 27 22 48 48 48h16a96 96 0 00192 0h128a96 96 0 00192 0h48c9 0 16-7 16-16v-32c0-9-7-16-16-16zM160 464a48 48 0 110-96 48 48 0 010 96zm320 0a48 48 0 110-96 48 48 0 010 96zm80-208H416V144h44l100 100v12z\"\/><\/svg><\/label>\r\n    <\/span>\r\n    <span style=\"display:none\">\r\n        <input type=\"text\" name=\"kc_honeypot\">\r\n    <\/span><\/span><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div style=\"width:100%;\">\n\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner full-width\" type=\"submit\" value=\"G\u00f6ndermek i\u00e7in\" \/>\n\t\t<\/p>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"tr\"\/><\/form>\n<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-72715256 > .col-inner {\n  border-radius: 8px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1219391222\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner box-shadow-1\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-zoom\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"380\" height=\"325\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/placa-de-publicidade-futebol.webp\" class=\"attachment-original size-original\" alt=\"futbol reklam panosu\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/placa-de-publicidade-futebol.webp 380w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/placa-de-publicidade-futebol-300x257.webp 300w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/placa-de-publicidade-futebol-14x12.webp 14w\" sizes=\"auto, (max-width: 380px) 100vw, 380px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n<h3>Futbol Reklam Kurulu<\/h3>\n<p>Stadyumlar i\u00e7in IP65 derecesine sahip, y\u00fcksek parlakl\u0131k ve ultra geni\u015f a\u00e7\u0131l\u0131 mod\u00fcler spor ekran\u0131.<\/p>\n<a href=\"#contact-form\" class=\"button primary is-outline\"  style=\"border-radius:99px;\">\n    <span>\u00dccretsiz fiyat teklifi<\/span>\n  <\/a>\n\n\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"contact-form\"\n\t     class=\"lightbox-by-id lightbox-content mfp-hide lightbox-white\"\n\t     style=\"max-width:800px ;padding:30px\">\n\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f5-o15\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"5\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o15\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"\u0130leti\u015fim formu\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o15\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"5\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f5-o15\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class='custom_contact_style'>\n\t<p><label> Ad\u0131n\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-nome\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"name\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"seu-nome\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> E-postan\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"seu-email\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> Mesaj\u0131n\u0131z (iste\u011fe ba\u011fl\u0131)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"sua-mensagem\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"sua-mensagem\"><\/textarea><\/span> <\/label>\n\t<\/p>\n\t<div style=\"margin-bottom:10px;\">\n\t\t<p><span class=\"wpcf7-form-control-wrap kc_captcha cf7ic-toggle\" data-name=\"kc_captcha\"><span class=\"wpcf7-form-control wpcf7-radio\"><span class=\"captcha-image\" style=\"display: none;\"><span class=\"cf7ic_instructions\">L\u00fctfen se\u00e7erek insan oldu\u011funuzu kan\u0131tlay\u0131n.<span> y\u0131ld\u0131z<\/span>.<\/span><label><input aria-label=\"1\" type=\"radio\" name=\"kc_captcha\" value=\"kc_human\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 576 512\"><path fill=\"currentColor\" d=\"M259 18l-65 132-146 22c-26 3-37 36-18 54l106 103-25 146c-5 26 23 46 46 33l131-68 131 68c23 13 51-7 46-33l-25-146 106-103c19-18 8-51-18-54l-146-22-65-132a32 32 0 00-58 0z\"\/><\/svg><\/label><label><input aria-label=\"2\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 640 512\"><path fill=\"currentColor\" d=\"M192 384h192c53 0 96-43 96-96h32a128 128 0 000-256H120c-13 0-24 11-24 24v232c0 53 43 96 96 96zM512 96a64 64 0 010 128h-32V96h32zm48 384H48c-47 0-61-64-36-64h584c25 0 11 64-36 64z\"\/><\/svg><\/label><label><input aria-label=\"3\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path fill=\"currentColor\" d=\"M350 99c-54 0-98-35-166-35-25 0-47 4-68 12a56 56 0 004-24C118 24 95 1 66 0a56 56 0 00-34 102v386c0 13 11 24 24 24h16c13 0 24-11 24-24v-94c28-12 64-23 114-23 54 0 98 35 166 35 48 0 86-16 122-41 9-6 14-15 14-26V96c0-23-24-39-45-29-35 16-77 32-117 32z\"\/><\/svg><\/label>\r\n    <\/span>\r\n    <span style=\"display:none\">\r\n        <input type=\"text\" name=\"kc_honeypot\">\r\n    <\/span><\/span><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div style=\"width:100%;\">\n\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner full-width\" type=\"submit\" value=\"G\u00f6ndermek i\u00e7in\" \/>\n\t\t<\/p>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"tr\"\/><\/form>\n<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1219391222 > .col-inner {\n  border-radius: 8px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-659030129\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner box-shadow-1\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-zoom\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"380\" height=\"325\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/placar-eletronico-poliesportivo.webp\" class=\"attachment-original size-original\" alt=\"\u00e7oklu spor elektronik skorboard\u0131\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/placar-eletronico-poliesportivo.webp 380w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/placar-eletronico-poliesportivo-300x257.webp 300w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/04\/placar-eletronico-poliesportivo-14x12.webp 14w\" sizes=\"auto, (max-width: 380px) 100vw, 380px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n<h3>Elektronik \u00c7oklu Spor Skor Tablosu<\/h3>\n<p>Entegre zamanlay\u0131c\u0131 ve \u00e7oklu m\u00fcsabaka senkronizasyonu ile HD spor yay\u0131n\u0131.<\/p>\n<a href=\"#contact-form\" class=\"button primary is-outline\"  style=\"border-radius:99px;\">\n    <span>\u00dccretsiz fiyat teklifi<\/span>\n  <\/a>\n\n\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"contact-form\"\n\t     class=\"lightbox-by-id lightbox-content mfp-hide lightbox-white\"\n\t     style=\"max-width:800px ;padding:30px\">\n\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f5-o16\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"5\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o16\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"\u0130leti\u015fim formu\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o16\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"5\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f5-o16\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class='custom_contact_style'>\n\t<p><label> Ad\u0131n\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-nome\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"name\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"seu-nome\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> E-postan\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"seu-email\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> Mesaj\u0131n\u0131z (iste\u011fe ba\u011fl\u0131)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"sua-mensagem\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"sua-mensagem\"><\/textarea><\/span> <\/label>\n\t<\/p>\n\t<div style=\"margin-bottom:10px;\">\n\t\t<p><span class=\"wpcf7-form-control-wrap kc_captcha cf7ic-toggle\" data-name=\"kc_captcha\"><span class=\"wpcf7-form-control wpcf7-radio\"><span class=\"captcha-image\" style=\"display: none;\"><span class=\"cf7ic_instructions\">L\u00fctfen se\u00e7erek insan oldu\u011funuzu kan\u0131tlay\u0131n.<span> y\u0131ld\u0131z<\/span>.<\/span><label><input aria-label=\"1\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 576 512\"><path fill=\"currentColor\" d=\"M415 24c-53 0-103 42-127 65-24-23-74-65-127-65C70 24 16 77 16 166c0 72 67 133 69 135l187 181c9 8 23 8 32 0l187-180c2-3 69-64 69-136 0-89-54-142-145-142z\"\/><\/svg><\/label><label><input aria-label=\"2\" type=\"radio\" name=\"kc_captcha\" value=\"kc_human\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 576 512\"><path fill=\"currentColor\" d=\"M259 18l-65 132-146 22c-26 3-37 36-18 54l106 103-25 146c-5 26 23 46 46 33l131-68 131 68c23 13 51-7 46-33l-25-146 106-103c19-18 8-51-18-54l-146-22-65-132a32 32 0 00-58 0z\"\/><\/svg><\/label><label><input aria-label=\"3\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path fill=\"currentColor\" d=\"M500 168h-55l-8-21a127 127 0 00-120-83H195a127 127 0 00-120 83l-8 21H12c-8 0-14 8-11 16l8 24a12 12 0 0011 8h29a64 64 0 00-33 56v48c0 16 6 31 16 42v62c0 13 11 24 24 24h48c13 0 24-11 24-24v-40h256v40c0 13 11 24 24 24h48c13 0 24-11 24-24v-62c10-11 16-26 16-42v-48c0-24-13-45-33-56h29a12 12 0 0011-8l8-24c3-8-3-16-11-16zm-365 2c9-25 33-42 60-42h122c27 0 51 17 60 42l15 38H120l15-38zM88 328a32 32 0 010-64c18 0 48 30 48 48s-30 16-48 16zm336 0c-18 0-48 2-48-16s30-48 48-48 32 14 32 32-14 32-32 32z\"\/><\/svg><\/label>\r\n    <\/span>\r\n    <span style=\"display:none\">\r\n        <input type=\"text\" name=\"kc_honeypot\">\r\n    <\/span><\/span><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div style=\"width:100%;\">\n\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner full-width\" type=\"submit\" value=\"G\u00f6ndermek i\u00e7in\" \/>\n\t\t<\/p>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"tr\"\/><\/form>\n<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-659030129 > .col-inner {\n  border-radius: 8px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1196479078 > .col-inner {\n  padding: 30px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_658693940 {\n  padding-top: 20px;\n  padding-bottom: 20px;\n  background-color: rgb(239, 248, 243);\n}\n@media (min-width:550px) {\n  #section_658693940 {\n    padding-top: 30px;\n    padding-bottom: 30px;\n  }\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section\" id=\"section_132616920\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row align-equal\"  id=\"row-521952442\">\n\n\n\t<div id=\"col-1411740256\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-2732122179\" class=\"text\">\n\t\t\n\n<h2><span style=\"font-size: 100%;\"><strong>Dijital Reklam Ekranlar\u0131nda Komple \u00c7\u00f6z\u00fcmler<\/strong><\/span><\/h2>\n\t\t\n<style>\n#text-2732122179 {\n  font-size: 1rem;\n  text-align: center;\n}\n@media (min-width:850px) {\n  #text-2732122179 {\n    font-size: 1.3rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-786753789\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-786753789 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<div class=\"row align-equal\"  id=\"row-150096701\">\n\n\n\t<div id=\"col-887538941\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner box-shadow-1\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-zoom\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"380\" height=\"325\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/totem-digital.webp\" class=\"attachment-original size-original\" alt=\"dijital totem\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/totem-digital.webp 380w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/totem-digital-300x257.webp 300w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/totem-digital-14x12.webp 14w\" sizes=\"auto, (max-width: 380px) 100vw, 380px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n<h3>Dijital Totem<\/h3>\n<p>Etkile\u015fimli dokunmatik \u00f6zelli\u011fe sahip ve yo\u011fun trafikli alanlarda \u00e7ok y\u00f6nl\u00fc kurulum imkan\u0131 sunan, reklam ama\u00e7l\u0131 ba\u011f\u0131ms\u0131z LCD ekran.<\/p>\n<a href=\"#contact-form\" class=\"button primary is-outline\"  style=\"border-radius:99px;\">\n    <span>\u00dccretsiz fiyat teklifi<\/span>\n  <\/a>\n\n\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"contact-form\"\n\t     class=\"lightbox-by-id lightbox-content mfp-hide lightbox-white\"\n\t     style=\"max-width:800px ;padding:30px\">\n\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f5-o17\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"5\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o17\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"\u0130leti\u015fim formu\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o17\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"5\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f5-o17\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class='custom_contact_style'>\n\t<p><label> Ad\u0131n\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-nome\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"name\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"seu-nome\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> E-postan\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"seu-email\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> Mesaj\u0131n\u0131z (iste\u011fe ba\u011fl\u0131)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"sua-mensagem\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"sua-mensagem\"><\/textarea><\/span> <\/label>\n\t<\/p>\n\t<div style=\"margin-bottom:10px;\">\n\t\t<p><span class=\"wpcf7-form-control-wrap kc_captcha cf7ic-toggle\" data-name=\"kc_captcha\"><span class=\"wpcf7-form-control wpcf7-radio\"><span class=\"captcha-image\" style=\"display: none;\"><span class=\"cf7ic_instructions\">L\u00fctfen se\u00e7erek insan oldu\u011funuzu kan\u0131tlay\u0131n.<span> a\u011fa\u00e7<\/span>.<\/span><label><input aria-label=\"1\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path fill=\"currentColor\" d=\"M512 176a176 176 0 01-209 173l-24 27a24 24 0 01-18 8h-37v40c0 13-11 24-24 24h-40v40c0 13-11 24-24 24H24c-13 0-24-11-24-24v-78c0-6 3-13 7-17l162-162a176 176 0 11343-55zm-176-48a48 48 0 1096 0 48 48 0 00-96 0z\"\/><\/svg><\/label><label><input aria-label=\"2\" type=\"radio\" name=\"kc_captcha\" value=\"kc_human\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 384 512\"><path fill=\"currentColor\" d=\"M377 375l-83-87h34c21 0 32-25 17-40l-82-88h33c21 0 32-25 18-40L210 8c-10-11-26-11-36 0L70 120c-14 15-3 40 18 40h33l-82 88c-15 15-4 40 17 40h34L7 375c-15 16-4 41 17 41h120c0 33-11 49-34 68-12 9-5 28 10 28h144c15 0 22-19 10-28-20-16-34-32-34-68h120c21 0 32-25 17-41z\"\/><\/svg><\/label><label><input aria-label=\"3\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 576 512\"><path fill=\"currentColor\" d=\"M472 200H360L256 6a12 12 0 00-10-6h-58c-8 0-14 7-12 15l34 185H100l-35-58a12 12 0 00-10-6H12c-8 0-13 7-12 14l21 106L0 362c-1 7 4 14 12 14h43c4 0 8-2 10-6l35-58h110l-34 185c-2 8 4 15 12 15h58a12 12 0 0010-6l104-194h112c57 0 104-25 104-56s-47-56-104-56z\"\/><\/svg><\/label>\r\n    <\/span>\r\n    <span style=\"display:none\">\r\n        <input type=\"text\" name=\"kc_honeypot\">\r\n    <\/span><\/span><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div style=\"width:100%;\">\n\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner full-width\" type=\"submit\" value=\"G\u00f6ndermek i\u00e7in\" \/>\n\t\t<\/p>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"tr\"\/><\/form>\n<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-887538941 > .col-inner {\n  border-radius: 8px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1982729086\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner box-shadow-1\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-zoom\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"380\" height=\"325\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/monitor-video-wall_.webp\" class=\"attachment-original size-original\" alt=\"monit\u00f6r video duvar\u0131\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/monitor-video-wall_.webp 380w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/monitor-video-wall_-300x257.webp 300w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/monitor-video-wall_-14x12.webp 14w\" sizes=\"auto, (max-width: 380px) 100vw, 380px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n<h3>Monit\u00f6r Video Duvar\u0131<\/h3>\n<p>Mod\u00fcler 4K LCD panelleri, ultra ince \u00e7er\u00e7eveleri ve 3 farkl\u0131 kal\u0131nl\u0131k se\u00e7ene\u011fi (3,5 mm\/5,5 mm\/8 mm) ile profesyonel video duvar \u00e7\u00f6z\u00fcm\u00fc.<\/p>\n<a href=\"#contact-form\" class=\"button primary is-outline\"  style=\"border-radius:99px;\">\n    <span>\u00dccretsiz fiyat teklifi<\/span>\n  <\/a>\n\n\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"contact-form\"\n\t     class=\"lightbox-by-id lightbox-content mfp-hide lightbox-white\"\n\t     style=\"max-width:800px ;padding:30px\">\n\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f5-o18\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"5\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o18\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"\u0130leti\u015fim formu\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o18\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"5\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f5-o18\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class='custom_contact_style'>\n\t<p><label> Ad\u0131n\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-nome\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"name\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"seu-nome\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> E-postan\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"seu-email\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> Mesaj\u0131n\u0131z (iste\u011fe ba\u011fl\u0131)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"sua-mensagem\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"sua-mensagem\"><\/textarea><\/span> <\/label>\n\t<\/p>\n\t<div style=\"margin-bottom:10px;\">\n\t\t<p><span class=\"wpcf7-form-control-wrap kc_captcha cf7ic-toggle\" data-name=\"kc_captcha\"><span class=\"wpcf7-form-control wpcf7-radio\"><span class=\"captcha-image\" style=\"display: none;\"><span class=\"cf7ic_instructions\">L\u00fctfen se\u00e7erek insan oldu\u011funuzu kan\u0131tlay\u0131n.<span> a\u011fa\u00e7<\/span>.<\/span><label><input aria-label=\"1\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 576 512\"><path fill=\"currentColor\" d=\"M488 313v143c0 13-11 24-24 24H348c-7 0-12-5-12-12V356c0-7-5-12-12-12h-72c-7 0-12 5-12 12v112c0 7-5 12-12 12H112c-13 0-24-11-24-24V313c0-4 2-7 4-10l188-154c5-4 11-4 16 0l188 154c2 3 4 6 4 10zm84-61l-84-69V44c0-6-5-12-12-12h-56c-7 0-12 6-12 12v73l-89-74a48 48 0 00-61 0L4 252c-5 4-5 12-1 17l25 31c5 5 12 5 17 1l235-193c5-4 11-4 16 0l235 193c5 5 13 4 17-1l25-31c4-6 4-13-1-17z\"\/><\/svg><\/label><label><input aria-label=\"2\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 640 512\"><path fill=\"currentColor\" d=\"M192 384h192c53 0 96-43 96-96h32a128 128 0 000-256H120c-13 0-24 11-24 24v232c0 53 43 96 96 96zM512 96a64 64 0 010 128h-32V96h32zm48 384H48c-47 0-61-64-36-64h584c25 0 11 64-36 64z\"\/><\/svg><\/label><label><input aria-label=\"3\" type=\"radio\" name=\"kc_captcha\" value=\"kc_human\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 384 512\"><path fill=\"currentColor\" d=\"M377 375l-83-87h34c21 0 32-25 17-40l-82-88h33c21 0 32-25 18-40L210 8c-10-11-26-11-36 0L70 120c-14 15-3 40 18 40h33l-82 88c-15 15-4 40 17 40h34L7 375c-15 16-4 41 17 41h120c0 33-11 49-34 68-12 9-5 28 10 28h144c15 0 22-19 10-28-20-16-34-32-34-68h120c21 0 32-25 17-41z\"\/><\/svg><\/label>\r\n    <\/span>\r\n    <span style=\"display:none\">\r\n        <input type=\"text\" name=\"kc_honeypot\">\r\n    <\/span><\/span><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div style=\"width:100%;\">\n\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner full-width\" type=\"submit\" value=\"G\u00f6ndermek i\u00e7in\" \/>\n\t\t<\/p>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"tr\"\/><\/form>\n<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1982729086 > .col-inner {\n  border-radius: 8px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-820447535\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner box-shadow-1\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-zoom\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"380\" height=\"325\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/kiosk.webp\" class=\"attachment-original size-original\" alt=\"k\u00f6\u015fk\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/kiosk.webp 380w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/kiosk-300x257.webp 300w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/kiosk-14x12.webp 14w\" sizes=\"auto, (max-width: 380px) 100vw, 380px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n<h3>Dijital Kiosk<\/h3>\n<p>Otonom hizmetler i\u00e7in dokunmatik ekranl\u0131, uzaktan g\u00fcncelleme \u00f6zellikli ve \u00f6zelle\u015ftirilebilir i\u00e7eri\u011fe sahip etkile\u015fimli terminal.<\/p>\n<a href=\"#contact-form\" class=\"button primary is-outline\"  style=\"border-radius:99px;\">\n    <span>\u00dccretsiz fiyat teklifi<\/span>\n  <\/a>\n\n\n\t<div id=\"contact-form\"\n\t     class=\"lightbox-by-id lightbox-content mfp-hide lightbox-white\"\n\t     style=\"max-width:800px ;padding:30px\">\n\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f5-o19\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"5\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o19\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"\u0130leti\u015fim formu\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o19\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"5\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f5-o19\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class='custom_contact_style'>\n\t<p><label> Ad\u0131n\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-nome\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"name\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"seu-nome\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> E-postan\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"seu-email\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> Mesaj\u0131n\u0131z (iste\u011fe ba\u011fl\u0131)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"sua-mensagem\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"sua-mensagem\"><\/textarea><\/span> <\/label>\n\t<\/p>\n\t<div style=\"margin-bottom:10px;\">\n\t\t<p><span class=\"wpcf7-form-control-wrap kc_captcha cf7ic-toggle\" data-name=\"kc_captcha\"><span class=\"wpcf7-form-control wpcf7-radio\"><span class=\"captcha-image\" style=\"display: none;\"><span class=\"cf7ic_instructions\">L\u00fctfen se\u00e7erek insan oldu\u011funuzu kan\u0131tlay\u0131n.<span> bardak<\/span>.<\/span><label><input aria-label=\"1\" type=\"radio\" name=\"kc_captcha\" value=\"kc_human\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 640 512\"><path fill=\"currentColor\" d=\"M192 384h192c53 0 96-43 96-96h32a128 128 0 000-256H120c-13 0-24 11-24 24v232c0 53 43 96 96 96zM512 96a64 64 0 010 128h-32V96h32zm48 384H48c-47 0-61-64-36-64h584c25 0 11 64-36 64z\"\/><\/svg><\/label><label><input aria-label=\"2\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path fill=\"currentColor\" d=\"M512 176a176 176 0 01-209 173l-24 27a24 24 0 01-18 8h-37v40c0 13-11 24-24 24h-40v40c0 13-11 24-24 24H24c-13 0-24-11-24-24v-78c0-6 3-13 7-17l162-162a176 176 0 11343-55zm-176-48a48 48 0 1096 0 48 48 0 00-96 0z\"\/><\/svg><\/label><label><input aria-label=\"3\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 576 512\"><path fill=\"currentColor\" d=\"M472 200H360L256 6a12 12 0 00-10-6h-58c-8 0-14 7-12 15l34 185H100l-35-58a12 12 0 00-10-6H12c-8 0-13 7-12 14l21 106L0 362c-1 7 4 14 12 14h43c4 0 8-2 10-6l35-58h110l-34 185c-2 8 4 15 12 15h58a12 12 0 0010-6l104-194h112c57 0 104-25 104-56s-47-56-104-56z\"\/><\/svg><\/label>\r\n    <\/span>\r\n    <span style=\"display:none\">\r\n        <input type=\"text\" name=\"kc_honeypot\">\r\n    <\/span><\/span><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div style=\"width:100%;\">\n\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner full-width\" type=\"submit\" value=\"G\u00f6ndermek i\u00e7in\" \/>\n\t\t<\/p>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"tr\"\/><\/form>\n<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-820447535 > .col-inner {\n  border-radius: 8px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1411740256 > .col-inner {\n  padding: 30px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1870568124\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"row align-equal\"  id=\"row-267520019\">\n\n\n\t<div id=\"col-1440002562\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner box-shadow-1\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-zoom\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"380\" height=\"325\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/lousa-digital.webp\" class=\"attachment-original size-original\" alt=\"dijital beyaz tahta\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/lousa-digital.webp 380w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/lousa-digital-300x257.webp 300w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/lousa-digital-14x12.webp 14w\" sizes=\"auto, (max-width: 380px) 100vw, 380px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n<h3>Dijital Beyaz Tahta<\/h3>\n<p>Toplant\u0131lar i\u00e7in \u00e7oklu dokunmatik, kablosuz payla\u015f\u0131m ve ultra h\u0131zl\u0131 yan\u0131t veren yazma \u00f6zelli\u011fine sahip 4K interaktif beyaz tahta.<\/p>\n<a href=\"#contact-form\" class=\"button primary is-outline\"  style=\"border-radius:99px;\">\n    <span>\u00dccretsiz fiyat teklifi<\/span>\n  <\/a>\n\n\n\t<div id=\"contact-form\"\n\t     class=\"lightbox-by-id lightbox-content mfp-hide lightbox-white\"\n\t     style=\"max-width:800px ;padding:30px\">\n\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f5-o20\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"5\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o20\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"\u0130leti\u015fim formu\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o20\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"5\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f5-o20\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class='custom_contact_style'>\n\t<p><label> Ad\u0131n\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-nome\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"name\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"seu-nome\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> E-postan\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"seu-email\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> Mesaj\u0131n\u0131z (iste\u011fe ba\u011fl\u0131)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"sua-mensagem\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"sua-mensagem\"><\/textarea><\/span> <\/label>\n\t<\/p>\n\t<div style=\"margin-bottom:10px;\">\n\t\t<p><span class=\"wpcf7-form-control-wrap kc_captcha cf7ic-toggle\" data-name=\"kc_captcha\"><span class=\"wpcf7-form-control wpcf7-radio\"><span class=\"captcha-image\" style=\"display: none;\"><span class=\"cf7ic_instructions\">L\u00fctfen se\u00e7erek insan oldu\u011funuzu kan\u0131tlay\u0131n.<span> bardak<\/span>.<\/span><label><input aria-label=\"1\" type=\"radio\" name=\"kc_captcha\" value=\"kc_human\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 640 512\"><path fill=\"currentColor\" d=\"M192 384h192c53 0 96-43 96-96h32a128 128 0 000-256H120c-13 0-24 11-24 24v232c0 53 43 96 96 96zM512 96a64 64 0 010 128h-32V96h32zm48 384H48c-47 0-61-64-36-64h584c25 0 11 64-36 64z\"\/><\/svg><\/label><label><input aria-label=\"2\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path fill=\"currentColor\" d=\"M512 176a176 176 0 01-209 173l-24 27a24 24 0 01-18 8h-37v40c0 13-11 24-24 24h-40v40c0 13-11 24-24 24H24c-13 0-24-11-24-24v-78c0-6 3-13 7-17l162-162a176 176 0 11343-55zm-176-48a48 48 0 1096 0 48 48 0 00-96 0z\"\/><\/svg><\/label><label><input aria-label=\"3\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 640 512\"><path fill=\"currentColor\" d=\"M624 352h-16V244c0-13-5-25-14-34L494 110c-9-9-21-14-34-14h-44V48c0-26-21-48-48-48H48C22 0 0 22 0 48v320c0 27 22 48 48 48h16a96 96 0 00192 0h128a96 96 0 00192 0h48c9 0 16-7 16-16v-32c0-9-7-16-16-16zM160 464a48 48 0 110-96 48 48 0 010 96zm320 0a48 48 0 110-96 48 48 0 010 96zm80-208H416V144h44l100 100v12z\"\/><\/svg><\/label>\r\n    <\/span>\r\n    <span style=\"display:none\">\r\n        <input type=\"text\" name=\"kc_honeypot\">\r\n    <\/span><\/span><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div style=\"width:100%;\">\n\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner full-width\" type=\"submit\" value=\"G\u00f6ndermek i\u00e7in\" \/>\n\t\t<\/p>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"tr\"\/><\/form>\n<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1440002562 > .col-inner {\n  border-radius: 8px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-86469999\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner box-shadow-1\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-zoom\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"380\" height=\"325\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/lousa-digital-escolar.webp\" class=\"attachment-original size-original\" alt=\"dijital okul beyaz tahtas\u0131\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/lousa-digital-escolar.webp 380w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/lousa-digital-escolar-300x257.webp 300w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/lousa-digital-escolar-14x12.webp 14w\" sizes=\"auto, (max-width: 380px) 100vw, 380px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n<h3>Okullar i\u00e7in Dijital Beyaz Tahta<\/h3>\n<p>Hassas dokunma, ak\u0131c\u0131 yazma ve an\u0131nda i\u00e7erik payla\u015f\u0131m\u0131 \u00f6zelliklerine sahip etkile\u015fimli 4K e\u011fitim \u00e7\u00f6z\u00fcm\u00fc.<\/p>\n<a href=\"#contact-form\" class=\"button primary is-outline\"  style=\"border-radius:99px;\">\n    <span>\u00dccretsiz fiyat teklifi<\/span>\n  <\/a>\n\n\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"contact-form\"\n\t     class=\"lightbox-by-id lightbox-content mfp-hide lightbox-white\"\n\t     style=\"max-width:800px ;padding:30px\">\n\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f5-o21\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"5\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o21\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"\u0130leti\u015fim formu\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o21\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"5\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f5-o21\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class='custom_contact_style'>\n\t<p><label> Ad\u0131n\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-nome\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"name\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"seu-nome\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> E-postan\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"seu-email\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> Mesaj\u0131n\u0131z (iste\u011fe ba\u011fl\u0131)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"sua-mensagem\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"sua-mensagem\"><\/textarea><\/span> <\/label>\n\t<\/p>\n\t<div style=\"margin-bottom:10px;\">\n\t\t<p><span class=\"wpcf7-form-control-wrap kc_captcha cf7ic-toggle\" data-name=\"kc_captcha\"><span class=\"wpcf7-form-control wpcf7-radio\"><span class=\"captcha-image\" style=\"display: none;\"><span class=\"cf7ic_instructions\">L\u00fctfen se\u00e7erek insan oldu\u011funuzu kan\u0131tlay\u0131n.<span> kalp<\/span>.<\/span><label><input aria-label=\"1\" type=\"radio\" name=\"kc_captcha\" value=\"kc_human\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 576 512\"><path fill=\"currentColor\" d=\"M415 24c-53 0-103 42-127 65-24-23-74-65-127-65C70 24 16 77 16 166c0 72 67 133 69 135l187 181c9 8 23 8 32 0l187-180c2-3 69-64 69-136 0-89-54-142-145-142z\"\/><\/svg><\/label><label><input aria-label=\"2\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path fill=\"currentColor\" d=\"M512 176a176 176 0 01-209 173l-24 27a24 24 0 01-18 8h-37v40c0 13-11 24-24 24h-40v40c0 13-11 24-24 24H24c-13 0-24-11-24-24v-78c0-6 3-13 7-17l162-162a176 176 0 11343-55zm-176-48a48 48 0 1096 0 48 48 0 00-96 0z\"\/><\/svg><\/label><label><input aria-label=\"3\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 576 512\"><path fill=\"currentColor\" d=\"M472 200H360L256 6a12 12 0 00-10-6h-58c-8 0-14 7-12 15l34 185H100l-35-58a12 12 0 00-10-6H12c-8 0-13 7-12 14l21 106L0 362c-1 7 4 14 12 14h43c4 0 8-2 10-6l35-58h110l-34 185c-2 8 4 15 12 15h58a12 12 0 0010-6l104-194h112c57 0 104-25 104-56s-47-56-104-56z\"\/><\/svg><\/label>\r\n    <\/span>\r\n    <span style=\"display:none\">\r\n        <input type=\"text\" name=\"kc_honeypot\">\r\n    <\/span><\/span><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div style=\"width:100%;\">\n\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner full-width\" type=\"submit\" value=\"G\u00f6ndermek i\u00e7in\" \/>\n\t\t<\/p>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"tr\"\/><\/form>\n<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-86469999 > .col-inner {\n  border-radius: 8px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-942004331\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner box-shadow-1\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-zoom\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"380\" height=\"325\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/digital-menu-boards.webp\" class=\"attachment-original size-original\" alt=\"Dijital Men\u00fc Panolar\u0131\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/digital-menu-boards.webp 380w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/digital-menu-boards-300x257.webp 300w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/digital-menu-boards-14x12.webp 14w\" sizes=\"auto, (max-width: 380px) 100vw, 380px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n<h3>Dijital Men\u00fc Panolar\u0131<\/h3>\n<p>Restoranlar i\u00e7in men\u00fclerin uzaktan an\u0131nda g\u00fcncellenmesini ve promosyonlar\u0131n ger\u00e7ek zamanl\u0131 olarak sunulmas\u0131n\u0131 sa\u011flayan dinamik \u00e7\u00f6z\u00fcm.<\/p>\n<a href=\"#contact-form\" class=\"button primary is-outline\"  style=\"border-radius:99px;\">\n    <span>\u00dccretsiz fiyat teklifi<\/span>\n  <\/a>\n\n\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"contact-form\"\n\t     class=\"lightbox-by-id lightbox-content mfp-hide lightbox-white\"\n\t     style=\"max-width:800px ;padding:30px\">\n\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f5-o22\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"5\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o22\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"\u0130leti\u015fim formu\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o22\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"5\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f5-o22\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class='custom_contact_style'>\n\t<p><label> Ad\u0131n\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-nome\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"name\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"seu-nome\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> E-postan\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"seu-email\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> Mesaj\u0131n\u0131z (iste\u011fe ba\u011fl\u0131)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"sua-mensagem\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"sua-mensagem\"><\/textarea><\/span> <\/label>\n\t<\/p>\n\t<div style=\"margin-bottom:10px;\">\n\t\t<p><span class=\"wpcf7-form-control-wrap kc_captcha cf7ic-toggle\" data-name=\"kc_captcha\"><span class=\"wpcf7-form-control wpcf7-radio\"><span class=\"captcha-image\" style=\"display: none;\"><span class=\"cf7ic_instructions\">L\u00fctfen se\u00e7erek insan oldu\u011funuzu kan\u0131tlay\u0131n.<span> kalp<\/span>.<\/span><label><input aria-label=\"1\" type=\"radio\" name=\"kc_captcha\" value=\"kc_human\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 576 512\"><path fill=\"currentColor\" d=\"M415 24c-53 0-103 42-127 65-24-23-74-65-127-65C70 24 16 77 16 166c0 72 67 133 69 135l187 181c9 8 23 8 32 0l187-180c2-3 69-64 69-136 0-89-54-142-145-142z\"\/><\/svg><\/label><label><input aria-label=\"2\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 576 512\"><path fill=\"currentColor\" d=\"M488 313v143c0 13-11 24-24 24H348c-7 0-12-5-12-12V356c0-7-5-12-12-12h-72c-7 0-12 5-12 12v112c0 7-5 12-12 12H112c-13 0-24-11-24-24V313c0-4 2-7 4-10l188-154c5-4 11-4 16 0l188 154c2 3 4 6 4 10zm84-61l-84-69V44c0-6-5-12-12-12h-56c-7 0-12 6-12 12v73l-89-74a48 48 0 00-61 0L4 252c-5 4-5 12-1 17l25 31c5 5 12 5 17 1l235-193c5-4 11-4 16 0l235 193c5 5 13 4 17-1l25-31c4-6 4-13-1-17z\"\/><\/svg><\/label><label><input aria-label=\"3\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 576 512\"><path fill=\"currentColor\" d=\"M472 200H360L256 6a12 12 0 00-10-6h-58c-8 0-14 7-12 15l34 185H100l-35-58a12 12 0 00-10-6H12c-8 0-13 7-12 14l21 106L0 362c-1 7 4 14 12 14h43c4 0 8-2 10-6l35-58h110l-34 185c-2 8 4 15 12 15h58a12 12 0 0010-6l104-194h112c57 0 104-25 104-56s-47-56-104-56z\"\/><\/svg><\/label>\r\n    <\/span>\r\n    <span style=\"display:none\">\r\n        <input type=\"text\" name=\"kc_honeypot\">\r\n    <\/span><\/span><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div style=\"width:100%;\">\n\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner full-width\" type=\"submit\" value=\"G\u00f6ndermek i\u00e7in\" \/>\n\t\t<\/p>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"tr\"\/><\/form>\n<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-942004331 > .col-inner {\n  border-radius: 8px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1870568124 > .col-inner {\n  padding: 30px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-357918730\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"row align-equal\"  id=\"row-1123577120\">\n\n\n\t<div id=\"col-1153718814\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner box-shadow-1\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-zoom\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"380\" height=\"325\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/portable-digital-signage.webp\" class=\"attachment-original size-original\" alt=\"ta\u015f\u0131nabilir dijital tabela\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/portable-digital-signage.webp 380w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/portable-digital-signage-300x257.webp 300w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/portable-digital-signage-14x12.webp 14w\" sizes=\"auto, (max-width: 380px) 100vw, 380px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n<h3>Ta\u015f\u0131nabilir Dijital Tabela<\/h3>\n<p>Ma\u011fazalar ve restoranlar i\u00e7in anl\u0131k uzaktan g\u00fcncellemeler sa\u011flayan dinamik ekranl\u0131 mobil \u00e7\u00f6z\u00fcm.<\/p>\n<a href=\"#contact-form\" class=\"button primary is-outline\"  style=\"border-radius:99px;\">\n    <span>\u00dccretsiz fiyat teklifi<\/span>\n  <\/a>\n\n\n\t<div id=\"contact-form\"\n\t     class=\"lightbox-by-id lightbox-content mfp-hide lightbox-white\"\n\t     style=\"max-width:800px ;padding:30px\">\n\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f5-o23\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"5\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o23\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"\u0130leti\u015fim formu\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o23\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"5\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f5-o23\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class='custom_contact_style'>\n\t<p><label> Ad\u0131n\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-nome\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"name\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"seu-nome\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> E-postan\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"seu-email\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> Mesaj\u0131n\u0131z (iste\u011fe ba\u011fl\u0131)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"sua-mensagem\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"sua-mensagem\"><\/textarea><\/span> <\/label>\n\t<\/p>\n\t<div style=\"margin-bottom:10px;\">\n\t\t<p><span class=\"wpcf7-form-control-wrap kc_captcha cf7ic-toggle\" data-name=\"kc_captcha\"><span class=\"wpcf7-form-control wpcf7-radio\"><span class=\"captcha-image\" style=\"display: none;\"><span class=\"cf7ic_instructions\">L\u00fctfen se\u00e7erek insan oldu\u011funuzu kan\u0131tlay\u0131n.<span> ev<\/span>.<\/span><label><input aria-label=\"1\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 576 512\"><path fill=\"currentColor\" d=\"M415 24c-53 0-103 42-127 65-24-23-74-65-127-65C70 24 16 77 16 166c0 72 67 133 69 135l187 181c9 8 23 8 32 0l187-180c2-3 69-64 69-136 0-89-54-142-145-142z\"\/><\/svg><\/label><label><input aria-label=\"2\" type=\"radio\" name=\"kc_captcha\" value=\"kc_human\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 576 512\"><path fill=\"currentColor\" d=\"M488 313v143c0 13-11 24-24 24H348c-7 0-12-5-12-12V356c0-7-5-12-12-12h-72c-7 0-12 5-12 12v112c0 7-5 12-12 12H112c-13 0-24-11-24-24V313c0-4 2-7 4-10l188-154c5-4 11-4 16 0l188 154c2 3 4 6 4 10zm84-61l-84-69V44c0-6-5-12-12-12h-56c-7 0-12 6-12 12v73l-89-74a48 48 0 00-61 0L4 252c-5 4-5 12-1 17l25 31c5 5 12 5 17 1l235-193c5-4 11-4 16 0l235 193c5 5 13 4 17-1l25-31c4-6 4-13-1-17z\"\/><\/svg><\/label><label><input aria-label=\"3\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 640 512\"><path fill=\"currentColor\" d=\"M192 384h192c53 0 96-43 96-96h32a128 128 0 000-256H120c-13 0-24 11-24 24v232c0 53 43 96 96 96zM512 96a64 64 0 010 128h-32V96h32zm48 384H48c-47 0-61-64-36-64h584c25 0 11 64-36 64z\"\/><\/svg><\/label>\r\n    <\/span>\r\n    <span style=\"display:none\">\r\n        <input type=\"text\" name=\"kc_honeypot\">\r\n    <\/span><\/span><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div style=\"width:100%;\">\n\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner full-width\" type=\"submit\" value=\"G\u00f6ndermek i\u00e7in\" \/>\n\t\t<\/p>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"tr\"\/><\/form>\n<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1153718814 > .col-inner {\n  border-radius: 8px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1167727806\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner box-shadow-1\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-zoom\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"380\" height=\"325\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/double-sided-lcd-screen.webp\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/double-sided-lcd-screen.webp 380w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/double-sided-lcd-screen-300x257.webp 300w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/double-sided-lcd-screen-14x12.webp 14w\" sizes=\"auto, (max-width: 380px) 100vw, 380px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n<h3>\u00c7ift tarafl\u0131 LCD ekran<\/h3>\n<p>\u00c7ift tarafl\u0131 4K ekranl\u0131, ayarlanabilir parlakl\u0131kl\u0131 ve ak\u0131ll\u0131 uzaktan kumandal\u0131 ask\u0131l\u0131 panel.<\/p>\n<a href=\"#contact-form\" class=\"button primary is-outline\"  style=\"border-radius:99px;\">\n    <span>\u00dccretsiz fiyat teklifi<\/span>\n  <\/a>\n\n\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"contact-form\"\n\t     class=\"lightbox-by-id lightbox-content mfp-hide lightbox-white\"\n\t     style=\"max-width:800px ;padding:30px\">\n\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f5-o24\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"5\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o24\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"\u0130leti\u015fim formu\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o24\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"5\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f5-o24\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class='custom_contact_style'>\n\t<p><label> Ad\u0131n\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-nome\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"name\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"seu-nome\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> E-postan\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"seu-email\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> Mesaj\u0131n\u0131z (iste\u011fe ba\u011fl\u0131)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"sua-mensagem\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"sua-mensagem\"><\/textarea><\/span> <\/label>\n\t<\/p>\n\t<div style=\"margin-bottom:10px;\">\n\t\t<p><span class=\"wpcf7-form-control-wrap kc_captcha cf7ic-toggle\" data-name=\"kc_captcha\"><span class=\"wpcf7-form-control wpcf7-radio\"><span class=\"captcha-image\" style=\"display: none;\"><span class=\"cf7ic_instructions\">L\u00fctfen se\u00e7erek insan oldu\u011funuzu kan\u0131tlay\u0131n.<span> bayrak<\/span>.<\/span><label><input aria-label=\"1\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 640 512\"><path fill=\"currentColor\" d=\"M192 384h192c53 0 96-43 96-96h32a128 128 0 000-256H120c-13 0-24 11-24 24v232c0 53 43 96 96 96zM512 96a64 64 0 010 128h-32V96h32zm48 384H48c-47 0-61-64-36-64h584c25 0 11 64-36 64z\"\/><\/svg><\/label><label><input aria-label=\"2\" type=\"radio\" name=\"kc_captcha\" value=\"kc_human\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path fill=\"currentColor\" d=\"M350 99c-54 0-98-35-166-35-25 0-47 4-68 12a56 56 0 004-24C118 24 95 1 66 0a56 56 0 00-34 102v386c0 13 11 24 24 24h16c13 0 24-11 24-24v-94c28-12 64-23 114-23 54 0 98 35 166 35 48 0 86-16 122-41 9-6 14-15 14-26V96c0-23-24-39-45-29-35 16-77 32-117 32z\"\/><\/svg><\/label><label><input aria-label=\"3\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 576 512\"><path fill=\"currentColor\" d=\"M472 200H360L256 6a12 12 0 00-10-6h-58c-8 0-14 7-12 15l34 185H100l-35-58a12 12 0 00-10-6H12c-8 0-13 7-12 14l21 106L0 362c-1 7 4 14 12 14h43c4 0 8-2 10-6l35-58h110l-34 185c-2 8 4 15 12 15h58a12 12 0 0010-6l104-194h112c57 0 104-25 104-56s-47-56-104-56z\"\/><\/svg><\/label>\r\n    <\/span>\r\n    <span style=\"display:none\">\r\n        <input type=\"text\" name=\"kc_honeypot\">\r\n    <\/span><\/span><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div style=\"width:100%;\">\n\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner full-width\" type=\"submit\" value=\"G\u00f6ndermek i\u00e7in\" \/>\n\t\t<\/p>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"tr\"\/><\/form>\n<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1167727806 > .col-inner {\n  border-radius: 8px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1897106103\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner box-shadow-1\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-zoom\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"380\" height=\"325\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/digital-signage.webp\" class=\"attachment-original size-original\" alt=\"dijital tabela\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/digital-signage.webp 380w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/digital-signage-300x257.webp 300w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/digital-signage-14x12.webp 14w\" sizes=\"auto, (max-width: 380px) 100vw, 380px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n<h3>Dijital Tabela<\/h3>\n<p>Duvara monte edilebilen, h\u0131zl\u0131 kurulumlu, dinamik 4K g\u00f6r\u00fcnt\u00fc sunan ve mobil uygulama \u00fczerinden uzaktan kontrol edilebilen LCD ekran.<\/p>\n<a href=\"#contact-form\" class=\"button primary is-outline\"  style=\"border-radius:99px;\">\n    <span>\u00dccretsiz fiyat teklifi<\/span>\n  <\/a>\n\n\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"contact-form\"\n\t     class=\"lightbox-by-id lightbox-content mfp-hide lightbox-white\"\n\t     style=\"max-width:800px ;padding:30px\">\n\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f5-o25\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"5\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o25\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"\u0130leti\u015fim formu\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o25\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"5\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f5-o25\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class='custom_contact_style'>\n\t<p><label> Ad\u0131n\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-nome\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"name\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"seu-nome\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> E-postan\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"seu-email\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> Mesaj\u0131n\u0131z (iste\u011fe ba\u011fl\u0131)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"sua-mensagem\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"sua-mensagem\"><\/textarea><\/span> <\/label>\n\t<\/p>\n\t<div style=\"margin-bottom:10px;\">\n\t\t<p><span class=\"wpcf7-form-control-wrap kc_captcha cf7ic-toggle\" data-name=\"kc_captcha\"><span class=\"wpcf7-form-control wpcf7-radio\"><span class=\"captcha-image\" style=\"display: none;\"><span class=\"cf7ic_instructions\">L\u00fctfen se\u00e7erek insan oldu\u011funuzu kan\u0131tlay\u0131n.<span> kamyon<\/span>.<\/span><label><input aria-label=\"1\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path fill=\"currentColor\" d=\"M500 168h-55l-8-21a127 127 0 00-120-83H195a127 127 0 00-120 83l-8 21H12c-8 0-14 8-11 16l8 24a12 12 0 0011 8h29a64 64 0 00-33 56v48c0 16 6 31 16 42v62c0 13 11 24 24 24h48c13 0 24-11 24-24v-40h256v40c0 13 11 24 24 24h48c13 0 24-11 24-24v-62c10-11 16-26 16-42v-48c0-24-13-45-33-56h29a12 12 0 0011-8l8-24c3-8-3-16-11-16zm-365 2c9-25 33-42 60-42h122c27 0 51 17 60 42l15 38H120l15-38zM88 328a32 32 0 010-64c18 0 48 30 48 48s-30 16-48 16zm336 0c-18 0-48 2-48-16s30-48 48-48 32 14 32 32-14 32-32 32z\"\/><\/svg><\/label><label><input aria-label=\"2\" type=\"radio\" name=\"kc_captcha\" value=\"kc_human\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 640 512\"><path fill=\"currentColor\" d=\"M624 352h-16V244c0-13-5-25-14-34L494 110c-9-9-21-14-34-14h-44V48c0-26-21-48-48-48H48C22 0 0 22 0 48v320c0 27 22 48 48 48h16a96 96 0 00192 0h128a96 96 0 00192 0h48c9 0 16-7 16-16v-32c0-9-7-16-16-16zM160 464a48 48 0 110-96 48 48 0 010 96zm320 0a48 48 0 110-96 48 48 0 010 96zm80-208H416V144h44l100 100v12z\"\/><\/svg><\/label><label><input aria-label=\"3\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 576 512\"><path fill=\"currentColor\" d=\"M472 200H360L256 6a12 12 0 00-10-6h-58c-8 0-14 7-12 15l34 185H100l-35-58a12 12 0 00-10-6H12c-8 0-13 7-12 14l21 106L0 362c-1 7 4 14 12 14h43c4 0 8-2 10-6l35-58h110l-34 185c-2 8 4 15 12 15h58a12 12 0 0010-6l104-194h112c57 0 104-25 104-56s-47-56-104-56z\"\/><\/svg><\/label>\r\n    <\/span>\r\n    <span style=\"display:none\">\r\n        <input type=\"text\" name=\"kc_honeypot\">\r\n    <\/span><\/span><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div style=\"width:100%;\">\n\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner full-width\" type=\"submit\" value=\"G\u00f6ndermek i\u00e7in\" \/>\n\t\t<\/p>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"tr\"\/><\/form>\n<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1897106103 > .col-inner {\n  border-radius: 8px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-357918730 > .col-inner {\n  padding: 30px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_132616920 {\n  padding-top: 40px;\n  padding-bottom: 40px;\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section\" id=\"section_887002327\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-width:1px 0px 1px 0px;\">\n\t<\/div>\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-large align-middle\"  id=\"row-569070821\">\n\n\n\t<div id=\"col-1291746717\" class=\"col medium-12 small-12 large-5\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-2282684494\" class=\"text\">\n\t\t\n\n<h2>LED Panel \u015eirketleri: 10 K\u00fcresel Sertifika ve 60 \u00dclkede ISO 9001<\/h2>\n\t\t\n<style>\n#text-2282684494 {\n  font-size: 1rem;\n  line-height: 1.5;\n}\n@media (min-width:850px) {\n  #text-2282684494 {\n    font-size: 1.2rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row\"  id=\"row-1200965392\">\n\n\n\t<div id=\"col-1964841445\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<p>20 y\u0131ld\u0131r LED ve LCD reklam ekranlar\u0131nda \u00e7\u00f6z\u00fcmler geli\u015ftiriyoruz. TELALED olarak, uluslararas\u0131 sertifikalar\u0131 (CE, RoHS, UL, CUL, FCC + 5 y\u00f6netmelikleri) ISO 9001 denetiminden ge\u00e7en \u00fcretim s\u00fcre\u00e7leriyle birle\u015ftiriyoruz \u2013 bile\u015fen se\u00e7iminden son kontrole kadar her ad\u0131m 14 kalite kontrol\u00fcnden ge\u00e7iyor. Bu titiz \u00f6l\u00e7\u00fct, 100&#039;den fazla \u00fclkede stadyumlar, havaalanlar\u0131 ve al\u0131\u015fveri\u015f merkezleri i\u00e7in istikrarl\u0131 g\u00f6rsel sistemler sunmam\u0131z\u0131 sa\u011fl\u0131yor. Se\u00e7iminiz \u015funlar\u0131 garanti eder: enerji uyumlulu\u011fu, elektromanyetik uyumluluk ve Avrupa, Amerika, Asya ve Orta Do\u011fu&#039;nun gereksinimlerini kar\u015f\u0131layan \u00e7evre sertifikal\u0131 malzemeler.<\/p>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1964841445 > .col-inner {\n  padding: 0px 0px 0px 0px;\n  margin: 0px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\n<style>\n#row-1200965392 > .col > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n<\/style>\n<\/div>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1291746717 > .col-inner {\n  padding: 0px 0px 0px 10px;\n  margin: 0px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-189831316\" class=\"col medium-1 small-12 large-1\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-164411683\" class=\"col medium-12 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"slider-wrapper relative\" id=\"slider-173094639\" >\n    <div class=\"slider slider-nav-circle slider-nav-large slider-nav-light slider-style-container\"\n        data-flickity-options='{            \"cellAlign\": \"center\",            \"imagesLoaded\": true,            \"lazyLoad\": 1,            \"freeScroll\": false,            \"wrapAround\": true,            \"autoPlay\": 4000,            \"pauseAutoPlayOnHover\" : true,            \"prevNextButtons\": true,            \"contain\" : true,            \"adaptiveHeight\" : true,            \"dragThreshold\" : 10,            \"percentPosition\": true,            \"pageDots\": true,            \"rightToLeft\": false,            \"draggable\": true,            \"selectedAttraction\": 0.1,            \"parallax\" : 0,            \"friction\": 0.6        }'\n        >\n        \n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1609254459\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:600px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"700\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/QUALIFICATION-HONOR.webp\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/QUALIFICATION-HONOR.webp 600w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/QUALIFICATION-HONOR-257x300.webp 257w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/QUALIFICATION-HONOR-10x12.webp 10w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1609254459 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1199766029\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:600px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"700\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/CE_EMC.webp\" class=\"attachment-original size-original\" alt=\"CE_EMC\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/CE_EMC.webp 600w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/CE_EMC-257x300.webp 257w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/CE_EMC-10x12.webp 10w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1199766029 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_919599968\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:600px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"700\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/CE_LVD.webp\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/CE_LVD.webp 600w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/CE_LVD-257x300.webp 257w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/CE_LVD-10x12.webp 10w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_919599968 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1095713894\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:600px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"700\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/Rohs.webp\" class=\"attachment-original size-original\" alt=\"Rohs\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/Rohs.webp 600w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/Rohs-257x300.webp 257w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/Rohs-10x12.webp 10w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1095713894 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n\t<\/div>\n\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-164411683 > .col-inner {\n  padding: 0px 10px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_887002327 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  background-color: rgb(239, 248, 243);\n}\n@media (min-width:850px) {\n  #section_887002327 {\n    padding-top: 80px;\n    padding-bottom: 80px;\n  }\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section\" id=\"section_1004062836\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-width:1px 0px 1px 0px;\">\n\t<\/div>\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-large align-middle\"  id=\"row-174683323\">\n\n\n\t<div id=\"col-17045549\" class=\"col medium-12 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"slider-wrapper relative\" id=\"slider-208501456\" >\n    <div class=\"slider slider-nav-circle slider-nav-large slider-nav-light slider-style-container\"\n        data-flickity-options='{            \"cellAlign\": \"center\",            \"imagesLoaded\": true,            \"lazyLoad\": 1,            \"freeScroll\": false,            \"wrapAround\": true,            \"autoPlay\": 4000,            \"pauseAutoPlayOnHover\" : true,            \"prevNextButtons\": true,            \"contain\" : true,            \"adaptiveHeight\" : true,            \"dragThreshold\" : 10,            \"percentPosition\": true,            \"pageDots\": true,            \"rightToLeft\": false,            \"draggable\": true,            \"selectedAttraction\": 0.1,            \"parallax\" : 0,            \"friction\": 0.6        }'\n        >\n        \n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_162396588\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:500px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"380\" height=\"500\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/engineer.webp\" class=\"attachment-original size-original\" alt=\"m\u00fchendis\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/engineer.webp 380w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/engineer-228x300.webp 228w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/engineer-9x12.webp 9w\" sizes=\"auto, (max-width: 380px) 100vw, 380px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_162396588 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_309217972\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:500px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"380\" height=\"500\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/services.webp\" class=\"attachment-original size-original\" alt=\"hizmetler\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/services.webp 380w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/services-228x300.webp 228w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/services-9x12.webp 9w\" sizes=\"auto, (max-width: 380px) 100vw, 380px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_309217972 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n\t<\/div>\n\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-17045549 > .col-inner {\n  padding: 0px 10px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1091525589\" class=\"col medium-1 small-12 large-1\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1672603266\" class=\"col medium-12 small-12 large-5\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-484198423\" class=\"text\">\n\t\t\n\n<h2>LED projeniz i\u00e7in \u00f6zel olarak tasarlanm\u0131\u015f \u00e7\u00f6z\u00fcmler.<\/h2>\n\t\t\n<style>\n#text-484198423 {\n  font-size: 1rem;\n  line-height: 1.5;\n}\n@media (min-width:850px) {\n  #text-484198423 {\n    font-size: 1.2rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row\"  id=\"row-912749164\">\n\n\n\t<div id=\"col-1597717637\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<p>Bizim <strong>sertifikal\u0131 teknik ekip<\/strong> Ekibinizin bir uzant\u0131s\u0131 gibi \u00e7al\u0131\u015f\u0131r. Sat\u0131n almadan \u00f6nce, alan\u0131n\u0131z\u0131 3D sim\u00fclasyonlarla haritaland\u0131r\u0131r ve IP65\/CE sertifikal\u0131 malzemeler se\u00e7menizde size rehberlik ederiz. Kurulumdan sonra, uzaktan izleme yoluyla \u00f6ng\u00f6r\u00fcc\u00fc bak\u0131m garantisi veriyoruz \u2013 otomatik g\u00fcncellemeler 86% ar\u0131zalar\u0131n\u0131 \u00f6nler. WhatsApp Business \u00fczerinden 15 dakikadan k\u0131sa s\u00fcrede yan\u0131t veren 7\/24 destek sunuyoruz.<\/p>\n<p>TELALED: \u0130lk pikselden m\u00fckemmel projeksiyona kadar bilimsel ortakl\u0131k.<\/p>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1597717637 > .col-inner {\n  padding: 0px 0px 0px 0px;\n  margin: 0px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\n<style>\n#row-912749164 > .col > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n<\/style>\n<\/div>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1672603266 > .col-inner {\n  padding: 0px 0px 0px 10px;\n  margin: 0px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1004062836 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n@media (min-width:850px) {\n  #section_1004062836 {\n    padding-top: 80px;\n    padding-bottom: 80px;\n  }\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section\" id=\"section_1595279397\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-1844283395\">\n\n\n\t<div id=\"col-1816101104\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-704251484\" class=\"text\">\n\t\t\n\n<h2>Entegre Fabrika: \u00dcretim S\u00fcrecinin Tamam\u0131nda Kalite Kontrol\u00fc<\/h2>\n\t\t\n<style>\n#text-704251484 {\n  font-size: 1.2rem;\n  line-height: 1.5;\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row\"  id=\"row-1846951741\">\n\n\n\t<div id=\"col-14838489\" class=\"col hide-for-medium medium-1 small-12 large-1\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-187566587\" class=\"col medium-10 small-12 large-10\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-630290238\" class=\"text\">\n\t\t\n\n<p>Ham maddeden nihai montaja kadar: \u00c7evre dostu sertifikal\u0131 s\u00fcre\u00e7lerle (ISO 9001\/CE) yeniden i\u015fleme maliyetlerinde 371.000 TL tasarruf. M\u00fchendislerimiz, zaman \u00e7izelgenizi 221.000 TL* h\u0131zland\u0131rmak i\u00e7in 18 temel g\u00f6stergeyi izliyor. Vizyonunuzu ger\u00e7ekle\u015ftirmenin m\u00fckemmel d\u00f6ng\u00fcs\u00fc.<\/p>\n\t\t\n<style>\n#text-630290238 {\n  text-align: left;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-866118963\" class=\"col hide-for-medium medium-1 small-12 large-1\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\t<div id=\"stack-3469965093\" class=\"stack stack-row justify-start items-stretch\">\n\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_5723588\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:440px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"443\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/smt-line-1.webp\" class=\"attachment-original size-original\" alt=\"smt-sat\u0131r\u0131\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/smt-line-1.webp 540w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/smt-line-1-300x246.webp 300w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/smt-line-1-15x12.webp 15w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_5723588 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_374382843\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:440px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"443\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/smt-line-2.webp\" class=\"attachment-original size-original\" alt=\"smt-sat\u0131r\u0131\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/smt-line-2.webp 540w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/smt-line-2-300x246.webp 300w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/smt-line-2-15x12.webp 15w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_374382843 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t\n<style>\n#stack-3469965093 > * {\n  --stack-gap: 2rem;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-770188527\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-770188527 {\n  padding-top: 20px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<h3>End\u00fcstriyel \u00f6l\u00e7ekte \u00fcretim kapasitesi, g\u00fcnde 1.000 m\u00b2&#039;den fazla \u00fcretim yapabiliyor.<\/h3>\n<div class=\"row\"  id=\"row-1248433342\">\n\n\n\t<div id=\"col-1956129255\" class=\"col hide-for-medium medium-1 small-12 large-1\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-179090336\" class=\"col medium-10 small-12 large-10\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-1742729497\" class=\"text\">\n\t\t\n\n<p>\u00c7in&#039;in Guangdong eyaletinde bulunan 3 fabrikam\u0131zda g\u00fcnde 100 adet LED\/LCD cihaz \u00fcretiyoruz. Esnek \u00fcretim hatlar\u0131m\u0131z, minimum 1 adetlik sipari\u015flerle \u00f6zelle\u015ftirilmi\u015f sipari\u015flere olanak tan\u0131yor. Uzmanla\u015fm\u0131\u015f lojistik a\u011f\u0131m\u0131z, Santos liman\u0131 \u00fczerinden Brezilya&#039;ya 18 g\u00fcn i\u00e7inde teslimat\u0131 garanti ediyor.<\/p>\n\t\t\n<style>\n#text-1742729497 {\n  text-align: left;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-453512912\" class=\"col hide-for-medium medium-1 small-12 large-1\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<a href=\"#contact-form\" class=\"button primary\"  style=\"border-radius:99px;\">\n    <span>\u00dccretsiz fiyat teklifi<\/span>\n  <\/a>\n\n\n\t<div id=\"gap-1973483820\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1973483820 {\n  padding-top: 40px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div id=\"contact-form\"\n\t     class=\"lightbox-by-id lightbox-content mfp-hide lightbox-white\"\n\t     style=\"max-width:800px ;padding:30px\">\n\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f5-o26\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"5\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o26\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"\u0130leti\u015fim formu\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o26\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"5\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f5-o26\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class='custom_contact_style'>\n\t<p><label> Ad\u0131n\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-nome\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"name\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"seu-nome\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> E-postan\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"seu-email\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> Mesaj\u0131n\u0131z (iste\u011fe ba\u011fl\u0131)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"sua-mensagem\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"sua-mensagem\"><\/textarea><\/span> <\/label>\n\t<\/p>\n\t<div style=\"margin-bottom:10px;\">\n\t\t<p><span class=\"wpcf7-form-control-wrap kc_captcha cf7ic-toggle\" data-name=\"kc_captcha\"><span class=\"wpcf7-form-control wpcf7-radio\"><span class=\"captcha-image\" style=\"display: none;\"><span class=\"cf7ic_instructions\">L\u00fctfen se\u00e7erek insan oldu\u011funuzu kan\u0131tlay\u0131n.<span> kalp<\/span>.<\/span><label><input aria-label=\"1\" type=\"radio\" name=\"kc_captcha\" value=\"kc_human\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 576 512\"><path fill=\"currentColor\" d=\"M415 24c-53 0-103 42-127 65-24-23-74-65-127-65C70 24 16 77 16 166c0 72 67 133 69 135l187 181c9 8 23 8 32 0l187-180c2-3 69-64 69-136 0-89-54-142-145-142z\"\/><\/svg><\/label><label><input aria-label=\"2\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path fill=\"currentColor\" d=\"M500 168h-55l-8-21a127 127 0 00-120-83H195a127 127 0 00-120 83l-8 21H12c-8 0-14 8-11 16l8 24a12 12 0 0011 8h29a64 64 0 00-33 56v48c0 16 6 31 16 42v62c0 13 11 24 24 24h48c13 0 24-11 24-24v-40h256v40c0 13 11 24 24 24h48c13 0 24-11 24-24v-62c10-11 16-26 16-42v-48c0-24-13-45-33-56h29a12 12 0 0011-8l8-24c3-8-3-16-11-16zm-365 2c9-25 33-42 60-42h122c27 0 51 17 60 42l15 38H120l15-38zM88 328a32 32 0 010-64c18 0 48 30 48 48s-30 16-48 16zm336 0c-18 0-48 2-48-16s30-48 48-48 32 14 32 32-14 32-32 32z\"\/><\/svg><\/label><label><input aria-label=\"3\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 640 512\"><path fill=\"currentColor\" d=\"M624 352h-16V244c0-13-5-25-14-34L494 110c-9-9-21-14-34-14h-44V48c0-26-21-48-48-48H48C22 0 0 22 0 48v320c0 27 22 48 48 48h16a96 96 0 00192 0h128a96 96 0 00192 0h48c9 0 16-7 16-16v-32c0-9-7-16-16-16zM160 464a48 48 0 110-96 48 48 0 010 96zm320 0a48 48 0 110-96 48 48 0 010 96zm80-208H416V144h44l100 100v12z\"\/><\/svg><\/label>\r\n    <\/span>\r\n    <span style=\"display:none\">\r\n        <input type=\"text\" name=\"kc_honeypot\">\r\n    <\/span><\/span><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div style=\"width:100%;\">\n\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner full-width\" type=\"submit\" value=\"G\u00f6ndermek i\u00e7in\" \/>\n\t\t<\/p>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"tr\"\/><\/form>\n<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1816101104 > .col-inner {\n  margin: 0px 0px -30px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1134271827\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"stack-3511106131\" class=\"stack stack-row justify-start items-stretch\">\n\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_2141295257\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:440px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"443\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/process-inspection-1.webp\" class=\"attachment-original size-original\" alt=\"s\u00fcre\u00e7 denetimi\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/process-inspection-1.webp 540w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/process-inspection-1-300x246.webp 300w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/process-inspection-1-15x12.webp 15w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_2141295257 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_153933330\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:440px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"443\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/process-inspection-2.webp\" class=\"attachment-original size-original\" alt=\"s\u00fcre\u00e7 denetimi\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/process-inspection-2.webp 540w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/process-inspection-2-300x246.webp 300w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/process-inspection-2-15x12.webp 15w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_153933330 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t\n<style>\n#stack-3511106131 > * {\n  --stack-gap: 2rem;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-155082798\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-155082798 {\n  padding-top: 20px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<h3>K\u00fcresel Son Teknoloji Ekranlama, Yerel Kontrol<\/h3>\n<div class=\"row\"  id=\"row-715562262\">\n\n\n\t<div id=\"col-612473434\" class=\"col hide-for-medium medium-1 small-12 large-1\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1903547076\" class=\"col medium-10 small-12 large-10\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-3640244599\" class=\"text\">\n\t\t\n\n<p>\u25a0 ISO\/IEC 17025 sertifikal\u0131 laboratuvar, \u00f6zellikle Brezilya i\u00e7in \u00e7evresel sim\u00fclasyonlar ger\u00e7ekle\u015ftirmektedir:<br \/>\u2713Y\u00fcksek nem odas\u0131nda 72 saat (ABNT NBR 15247&#039;ye g\u00f6re 85%RH)<br \/>\u2713Kuzeydo\u011fu Brezilya&#039;ya benzer s\u0131cakl\u0131k de\u011fi\u015fimleriyle (-20\u00b0C\u219450\u00b0C) yap\u0131lan stres testi<br \/>\u25a0 ABNT sertifikas\u0131na sahip \u00c7inli m\u00fchendisler, sevkiyat \u00f6ncesinde interaktif video konferans yoluyla konfig\u00fcrasyonlar\u0131 do\u011frulayarak \u015funlar\u0131 sa\u011flarlar:<br \/>\u2713127V\/220V elektrik \u015febekeleriyle uyumludur<br \/>\u2713Brezilya saat diliminin otomatik yap\u0131land\u0131r\u0131lmas\u0131<\/p>\n\t\t\n<style>\n#text-3640244599 {\n  text-align: left;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1222475621\" class=\"col hide-for-medium medium-1 small-12 large-1\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<a href=\"#contact-form\" class=\"button primary\"  style=\"border-radius:99px;\">\n    <span>\u00dccretsiz fiyat teklifi<\/span>\n  <\/a>\n\n\n\t<div id=\"gap-599517686\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-599517686 {\n  padding-top: 40px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div id=\"contact-form\"\n\t     class=\"lightbox-by-id lightbox-content mfp-hide lightbox-white\"\n\t     style=\"max-width:800px ;padding:30px\">\n\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f5-o27\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"5\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o27\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"\u0130leti\u015fim formu\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o27\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"5\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f5-o27\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class='custom_contact_style'>\n\t<p><label> Ad\u0131n\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-nome\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"name\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"seu-nome\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> E-postan\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"seu-email\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> Mesaj\u0131n\u0131z (iste\u011fe ba\u011fl\u0131)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"sua-mensagem\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"sua-mensagem\"><\/textarea><\/span> <\/label>\n\t<\/p>\n\t<div style=\"margin-bottom:10px;\">\n\t\t<p><span class=\"wpcf7-form-control-wrap kc_captcha cf7ic-toggle\" data-name=\"kc_captcha\"><span class=\"wpcf7-form-control wpcf7-radio\"><span class=\"captcha-image\" style=\"display: none;\"><span class=\"cf7ic_instructions\">L\u00fctfen se\u00e7erek insan oldu\u011funuzu kan\u0131tlay\u0131n.<span> bardak<\/span>.<\/span><label><input aria-label=\"1\" type=\"radio\" name=\"kc_captcha\" value=\"kc_human\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 640 512\"><path fill=\"currentColor\" d=\"M192 384h192c53 0 96-43 96-96h32a128 128 0 000-256H120c-13 0-24 11-24 24v232c0 53 43 96 96 96zM512 96a64 64 0 010 128h-32V96h32zm48 384H48c-47 0-61-64-36-64h584c25 0 11 64-36 64z\"\/><\/svg><\/label><label><input aria-label=\"2\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path fill=\"currentColor\" d=\"M350 99c-54 0-98-35-166-35-25 0-47 4-68 12a56 56 0 004-24C118 24 95 1 66 0a56 56 0 00-34 102v386c0 13 11 24 24 24h16c13 0 24-11 24-24v-94c28-12 64-23 114-23 54 0 98 35 166 35 48 0 86-16 122-41 9-6 14-15 14-26V96c0-23-24-39-45-29-35 16-77 32-117 32z\"\/><\/svg><\/label><label><input aria-label=\"3\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 640 512\"><path fill=\"currentColor\" d=\"M624 352h-16V244c0-13-5-25-14-34L494 110c-9-9-21-14-34-14h-44V48c0-26-21-48-48-48H48C22 0 0 22 0 48v320c0 27 22 48 48 48h16a96 96 0 00192 0h128a96 96 0 00192 0h48c9 0 16-7 16-16v-32c0-9-7-16-16-16zM160 464a48 48 0 110-96 48 48 0 010 96zm320 0a48 48 0 110-96 48 48 0 010 96zm80-208H416V144h44l100 100v12z\"\/><\/svg><\/label>\r\n    <\/span>\r\n    <span style=\"display:none\">\r\n        <input type=\"text\" name=\"kc_honeypot\">\r\n    <\/span><\/span><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div style=\"width:100%;\">\n\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner full-width\" type=\"submit\" value=\"G\u00f6ndermek i\u00e7in\" \/>\n\t\t<\/p>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"tr\"\/><\/form>\n<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1134271827 > .col-inner {\n  margin: 0px 0px -30px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1686961709\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"stack-3444913857\" class=\"stack stack-row justify-start items-stretch\">\n\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_735862099\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:440px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"443\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/assembly-line-1.webp\" class=\"attachment-original size-original\" alt=\"montaj hatt\u0131\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/assembly-line-1.webp 540w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/assembly-line-1-300x246.webp 300w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/assembly-line-1-15x12.webp 15w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_735862099 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_151009913\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:440px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"443\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/assembly-line-2.webp\" class=\"attachment-original size-original\" alt=\"montaj hatt\u0131\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/assembly-line-2.webp 540w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/assembly-line-2-300x246.webp 300w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/assembly-line-2-15x12.webp 15w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_151009913 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t\n<style>\n#stack-3444913857 > * {\n  --stack-gap: 2rem;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-282894517\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-282894517 {\n  padding-top: 20px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<h3>Tropikal iklimlerde uzmanla\u015fan bu ekran, g\u00fc\u00e7l\u00fc \u00e7evresel uyum yetene\u011fine sahiptir.<\/h3>\n<div class=\"row\"  id=\"row-897071241\">\n\n\n\t<div id=\"col-49104973\" class=\"col hide-for-medium medium-1 small-12 large-1\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-770720677\" class=\"col medium-10 small-12 large-10\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-3278510363\" class=\"text\">\n\t\t\n\n<p>Salvador, Fortaleza ve Bel\u00e9m&#039;de tamamlanan 27 proje, ekranlar\u0131m\u0131z\u0131n 45\u00b0C&#039;ye kadar nem seviyelerine dayanabildi\u011fini kan\u0131tl\u0131yor. Korozyon \u00f6nleyici nano kaplamal\u0131 devre kartlar\u0131 ve yapay zeka destekli solma \u00f6nleyici algoritma, Brezilya&#039;da 3.500&#039;den fazla ekran\u0131 koruma alt\u0131na ald\u0131.<\/p>\n\t\t\n<style>\n#text-3278510363 {\n  text-align: left;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1905612360\" class=\"col hide-for-medium medium-1 small-12 large-1\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<a href=\"#contact-form\" class=\"button primary\"  style=\"border-radius:99px;\">\n    <span>\u00dccretsiz fiyat teklifi<\/span>\n  <\/a>\n\n\n\t<div id=\"gap-1631863195\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1631863195 {\n  padding-top: 40px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div id=\"contact-form\"\n\t     class=\"lightbox-by-id lightbox-content mfp-hide lightbox-white\"\n\t     style=\"max-width:800px ;padding:30px\">\n\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f5-o28\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"5\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o28\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"\u0130leti\u015fim formu\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o28\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"5\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f5-o28\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class='custom_contact_style'>\n\t<p><label> Ad\u0131n\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-nome\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"name\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"seu-nome\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> E-postan\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"seu-email\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> Mesaj\u0131n\u0131z (iste\u011fe ba\u011fl\u0131)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"sua-mensagem\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"sua-mensagem\"><\/textarea><\/span> <\/label>\n\t<\/p>\n\t<div style=\"margin-bottom:10px;\">\n\t\t<p><span class=\"wpcf7-form-control-wrap kc_captcha cf7ic-toggle\" data-name=\"kc_captcha\"><span class=\"wpcf7-form-control wpcf7-radio\"><span class=\"captcha-image\" style=\"display: none;\"><span class=\"cf7ic_instructions\">L\u00fctfen se\u00e7erek insan oldu\u011funuzu kan\u0131tlay\u0131n.<span> u\u00e7ak<\/span>.<\/span><label><input aria-label=\"1\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 576 512\"><path fill=\"currentColor\" d=\"M259 18l-65 132-146 22c-26 3-37 36-18 54l106 103-25 146c-5 26 23 46 46 33l131-68 131 68c23 13 51-7 46-33l-25-146 106-103c19-18 8-51-18-54l-146-22-65-132a32 32 0 00-58 0z\"\/><\/svg><\/label><label><input aria-label=\"2\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path fill=\"currentColor\" d=\"M350 99c-54 0-98-35-166-35-25 0-47 4-68 12a56 56 0 004-24C118 24 95 1 66 0a56 56 0 00-34 102v386c0 13 11 24 24 24h16c13 0 24-11 24-24v-94c28-12 64-23 114-23 54 0 98 35 166 35 48 0 86-16 122-41 9-6 14-15 14-26V96c0-23-24-39-45-29-35 16-77 32-117 32z\"\/><\/svg><\/label><label><input aria-label=\"3\" type=\"radio\" name=\"kc_captcha\" value=\"kc_human\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 576 512\"><path fill=\"currentColor\" d=\"M472 200H360L256 6a12 12 0 00-10-6h-58c-8 0-14 7-12 15l34 185H100l-35-58a12 12 0 00-10-6H12c-8 0-13 7-12 14l21 106L0 362c-1 7 4 14 12 14h43c4 0 8-2 10-6l35-58h110l-34 185c-2 8 4 15 12 15h58a12 12 0 0010-6l104-194h112c57 0 104-25 104-56s-47-56-104-56z\"\/><\/svg><\/label>\r\n    <\/span>\r\n    <span style=\"display:none\">\r\n        <input type=\"text\" name=\"kc_honeypot\">\r\n    <\/span><\/span><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div style=\"width:100%;\">\n\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner full-width\" type=\"submit\" value=\"G\u00f6ndermek i\u00e7in\" \/>\n\t\t<\/p>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"tr\"\/><\/form>\n<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1686961709 > .col-inner {\n  margin: 0px 0px -30px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1767771840\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"stack-3130000258\" class=\"stack stack-row justify-start items-stretch\">\n\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1893619730\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:440px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"443\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/aging-lines-1.webp\" class=\"attachment-original size-original\" alt=\"ya\u015flanma \u00e7izgileri\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/aging-lines-1.webp 540w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/aging-lines-1-300x246.webp 300w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/aging-lines-1-15x12.webp 15w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1893619730 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_184865790\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:440px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"443\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/aging-line-2.webp\" class=\"attachment-original size-original\" alt=\"ya\u015flanma \u00e7izgileri\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/aging-line-2.webp 540w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/aging-line-2-300x246.webp 300w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/aging-line-2-15x12.webp 15w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_184865790 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t\n<style>\n#stack-3130000258 > * {\n  --stack-gap: 2rem;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-1521705224\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1521705224 {\n  padding-top: 20px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<h3>Sefer \u00d6ncesi Ya\u015flanma Testi<\/h3>\n<div class=\"row\"  id=\"row-2145636670\">\n\n\n\t<div id=\"col-666893693\" class=\"col hide-for-medium medium-1 small-12 large-1\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-600295678\" class=\"col medium-10 small-12 large-10\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-674561592\" class=\"text\">\n\t\t\n\n<p>\u2714 72 saat kesintisiz test<br \/>55\u00b0C&#039;de (tropikal sim\u00fclasyon) beyaz bir arka plan \u00fczerinde 7000 nit parlakl\u0131k.<br \/>Dinamik parlakl\u0131k d\u00f6ng\u00fcleri (her 5 dakikada bir 100%\u219450%)<br \/>\u2714 \u00dc\u00e7l\u00fc Do\u011frulama<br \/>TELALED DIAG arac\u0131l\u0131\u011f\u0131yla otomatik \u00f6l\u00fc piksel tespiti (&lt;5ppm)<br \/>HDMI 2.1 sinyal stres testi (4K@120Hz e\u015f zamanl\u0131)<br \/>35\u00b0C&#039;de su ile IP65 onayl\u0131d\u0131r (ABNT NBR 15247).<\/p>\n\t\t\n<style>\n#text-674561592 {\n  text-align: left;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1628496954\" class=\"col hide-for-medium medium-1 small-12 large-1\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<a href=\"#contact-form\" class=\"button primary\"  style=\"border-radius:99px;\">\n    <span>\u00dccretsiz fiyat teklifi<\/span>\n  <\/a>\n\n\n\t<div id=\"gap-30679749\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-30679749 {\n  padding-top: 40px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div id=\"contact-form\"\n\t     class=\"lightbox-by-id lightbox-content mfp-hide lightbox-white\"\n\t     style=\"max-width:800px ;padding:30px\">\n\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f5-o29\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"5\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o29\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"\u0130leti\u015fim formu\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o29\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"5\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f5-o29\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class='custom_contact_style'>\n\t<p><label> Ad\u0131n\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-nome\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"name\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"seu-nome\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> E-postan\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"seu-email\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> Mesaj\u0131n\u0131z (iste\u011fe ba\u011fl\u0131)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"sua-mensagem\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"sua-mensagem\"><\/textarea><\/span> <\/label>\n\t<\/p>\n\t<div style=\"margin-bottom:10px;\">\n\t\t<p><span class=\"wpcf7-form-control-wrap kc_captcha cf7ic-toggle\" data-name=\"kc_captcha\"><span class=\"wpcf7-form-control wpcf7-radio\"><span class=\"captcha-image\" style=\"display: none;\"><span class=\"cf7ic_instructions\">L\u00fctfen se\u00e7erek insan oldu\u011funuzu kan\u0131tlay\u0131n.<span> araba<\/span>.<\/span><label><input aria-label=\"1\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 576 512\"><path fill=\"currentColor\" d=\"M488 313v143c0 13-11 24-24 24H348c-7 0-12-5-12-12V356c0-7-5-12-12-12h-72c-7 0-12 5-12 12v112c0 7-5 12-12 12H112c-13 0-24-11-24-24V313c0-4 2-7 4-10l188-154c5-4 11-4 16 0l188 154c2 3 4 6 4 10zm84-61l-84-69V44c0-6-5-12-12-12h-56c-7 0-12 6-12 12v73l-89-74a48 48 0 00-61 0L4 252c-5 4-5 12-1 17l25 31c5 5 12 5 17 1l235-193c5-4 11-4 16 0l235 193c5 5 13 4 17-1l25-31c4-6 4-13-1-17z\"\/><\/svg><\/label><label><input aria-label=\"2\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 576 512\"><path fill=\"currentColor\" d=\"M259 18l-65 132-146 22c-26 3-37 36-18 54l106 103-25 146c-5 26 23 46 46 33l131-68 131 68c23 13 51-7 46-33l-25-146 106-103c19-18 8-51-18-54l-146-22-65-132a32 32 0 00-58 0z\"\/><\/svg><\/label><label><input aria-label=\"3\" type=\"radio\" name=\"kc_captcha\" value=\"kc_human\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path fill=\"currentColor\" d=\"M500 168h-55l-8-21a127 127 0 00-120-83H195a127 127 0 00-120 83l-8 21H12c-8 0-14 8-11 16l8 24a12 12 0 0011 8h29a64 64 0 00-33 56v48c0 16 6 31 16 42v62c0 13 11 24 24 24h48c13 0 24-11 24-24v-40h256v40c0 13 11 24 24 24h48c13 0 24-11 24-24v-62c10-11 16-26 16-42v-48c0-24-13-45-33-56h29a12 12 0 0011-8l8-24c3-8-3-16-11-16zm-365 2c9-25 33-42 60-42h122c27 0 51 17 60 42l15 38H120l15-38zM88 328a32 32 0 010-64c18 0 48 30 48 48s-30 16-48 16zm336 0c-18 0-48 2-48-16s30-48 48-48 32 14 32 32-14 32-32 32z\"\/><\/svg><\/label>\r\n    <\/span>\r\n    <span style=\"display:none\">\r\n        <input type=\"text\" name=\"kc_honeypot\">\r\n    <\/span><\/span><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div style=\"width:100%;\">\n\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner full-width\" type=\"submit\" value=\"G\u00f6ndermek i\u00e7in\" \/>\n\t\t<\/p>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"tr\"\/><\/form>\n<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1767771840 > .col-inner {\n  margin: 0px 0px -30px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1595279397 {\n  padding-top: 40px;\n  padding-bottom: 40px;\n  margin-bottom: 0px;\n  background-color: rgb(239, 248, 243);\n}\n@media (min-width:550px) {\n  #section_1595279397 {\n    padding-top: 80px;\n    padding-bottom: 80px;\n  }\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section\" id=\"section_426521954\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-1257499814\">\n\n\n\t<div id=\"col-928292795\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-663586174\" class=\"text\">\n\t\t\n\n<h2><strong>LED&#039;lerde TELALED neden en iyi se\u00e7iminiz?<\/strong><\/h2>\n\t\t\n<style>\n#text-663586174 {\n  font-size: 1.2rem;\n  line-height: 1.5;\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n<p>20 y\u0131l\u0131 a\u015fk\u0131n sekt\u00f6r liderli\u011fimiz, k\u00fcresel sertifikalar\u0131m\u0131z ve 30.000 m\u00b2&#039;lik fabrikam\u0131zla, Portekizce dilinde 7\/24 destek sunan y\u00fcksek performansl\u0131 ekranlar sunuyoruz. 102 \u00fclkede 40.000 proje teslim ettik, 251.000 TL tasarruf ve 301.000 TL daha h\u0131zl\u0131 teslimat garantisi veriyoruz. Kan\u0131tlanm\u0131\u015f sonu\u00e7lar, uygun fiyat.<\/p>\n<div class=\"slider-wrapper relative\" id=\"slider-441380435\" >\n    <div class=\"slider slider-nav-dots-dashes-spaced slider-nav-simple slider-nav-large slider-nav-dark slider-style-normal\"\n        data-flickity-options='{            \"cellAlign\": \"center\",            \"imagesLoaded\": true,            \"lazyLoad\": 1,            \"freeScroll\": false,            \"wrapAround\": true,            \"autoPlay\": 5000,            \"pauseAutoPlayOnHover\" : true,            \"prevNextButtons\": true,            \"contain\" : true,            \"adaptiveHeight\" : true,            \"dragThreshold\" : 10,            \"percentPosition\": true,            \"pageDots\": true,            \"rightToLeft\": false,            \"draggable\": true,            \"selectedAttraction\": 0.1,            \"parallax\" : 0,            \"friction\": 0.6        }'\n        >\n        \n\n<div class=\"row align-equal\"  id=\"row-479095008\">\n\n\n\t<div id=\"col-1603612760\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner box-shadow-1\" style=\"background-color:rgb(255,255,255);\" >\n\t\t\t\n\t\t\t\n\n\t<div id=\"gap-1012983365\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1012983365 {\n  padding-top: 15px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 150px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/since-2003-4.webp\" class=\"attachment-medium size-medium\" alt=\"2003&#039;ten beri\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/since-2003-4.webp 200w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/since-2003-4-150x150.webp 150w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/since-2003-4-12x12.webp 12w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/since-2003-4-100x100.webp 100w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n<div class=\"row align-center\"  id=\"row-57626691\">\n\n\n\t<div id=\"col-1072132787\" class=\"col medium-11 small-11 large-11\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h3><strong>2003&#039;ten Beri Sekt\u00f6r Lideri<\/strong><\/h3>\n<p>20 y\u0131l\u0131 a\u015fk\u0131n s\u00fcredir aral\u0131ks\u0131z yenilik\u00e7ilikle, 102 \u00fclkede 40.000&#039;den fazla m\u00fc\u015fteriye hizmet veriyoruz. Ola\u011fan\u00fcst\u00fc de\u011fer ve 7\/24 hizmetimizle fikirleri k\u00fcresel projelere d\u00f6n\u00fc\u015ft\u00fcr\u00fcyoruz.<\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1603612760 > .col-inner {\n  border-radius: 8px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-517067826\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner box-shadow-1\" style=\"background-color:rgb(255,255,255);\" >\n\t\t\t\n\t\t\t\n\n\t<div id=\"gap-1307570496\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1307570496 {\n  padding-top: 15px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 150px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/certificate.webp\" class=\"attachment-medium size-medium\" alt=\"sertifika simgesi\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/certificate.webp 200w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/certificate-150x150.webp 150w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/certificate-12x12.webp 12w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/certificate-100x100.webp 100w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n<div class=\"row align-center\"  id=\"row-1118496184\">\n\n\n\t<div id=\"col-2084974556\" class=\"col medium-11 small-11 large-11\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h3><strong>K\u00fcresel Olarak Sertifikal\u0131 Kalite<\/strong><\/h3>\n<p>Nationstar \u00e7ipli ekranlar ve 12 sertifika (CE\/KC\/SABER) taraf\u0131ndan onaylanm\u0131\u015f IP65 dereceli kabinler. &lt;0.012% hata oran\u0131yla 10 a\u015famal\u0131 kalite kontrol\u00fc.<\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-517067826 > .col-inner {\n  border-radius: 8px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-101187975\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner box-shadow-1\" style=\"background-color:rgb(255,255,255);\" >\n\t\t\t\n\t\t\t\n\n\t<div id=\"gap-858771994\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-858771994 {\n  padding-top: 15px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 150px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/Fabrica.webp\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/Fabrica.webp 200w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/Fabrica-150x150.webp 150w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/Fabrica-12x12.webp 12w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/Fabrica-100x100.webp 100w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n<div class=\"row align-center\"  id=\"row-334308137\">\n\n\n\t<div id=\"col-2088830113\" class=\"col medium-11 small-11 large-11\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h3><strong>Geli\u015fmi\u015f M\u00fchendislik Fabrikas\u0131<\/strong><\/h3>\n<p>50&#039;den fazla CNC makinesine sahip 30.000 m\u00b2&#039;lik end\u00fcstriyel kompleks. 50 uzman m\u00fchendis, sekt\u00f6r standartlar\u0131ndan daha h\u0131zl\u0131 teslimat s\u00fcresi sa\u011fl\u0131yor.<\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-101187975 > .col-inner {\n  border-radius: 8px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1417222903\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner box-shadow-1\" style=\"background-color:rgb(255,255,255);\" >\n\t\t\t\n\t\t\t\n\n\t<div id=\"gap-1940120778\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1940120778 {\n  padding-top: 15px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 150px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/Economia-Inteligente.webp\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/Economia-Inteligente.webp 200w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/Economia-Inteligente-150x150.webp 150w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/Economia-Inteligente-12x12.webp 12w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/Economia-Inteligente-100x100.webp 100w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n<div class=\"row align-center\"  id=\"row-835835920\">\n\n\n\t<div id=\"col-1696076621\" class=\"col medium-11 small-11 large-11\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h3><strong>Ak\u0131ll\u0131 Ekonomi<\/strong><\/h3>\n<p>Kurulumdan bak\u0131ma kadar daha d\u00fc\u015f\u00fck toplam maliyetli \u00e7\u00f6z\u00fcmler. Stratejik ortaklar i\u00e7in 5 y\u0131ll\u0131k uzat\u0131lm\u0131\u015f garantili VIP programlar\u0131.<\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1417222903 > .col-inner {\n  border-radius: 8px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row align-equal\"  id=\"row-707784154\">\n\n\n\t<div id=\"col-665687507\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner box-shadow-1\" style=\"background-color:rgb(255, 255, 255);\" >\n\t\t\t\n\t\t\t\n\n\t<div id=\"gap-194091264\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-194091264 {\n  padding-top: 15px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 150px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/Aliancas-Estrategicas.webp\" class=\"attachment-medium size-medium\" alt=\"Stratejik \u0130ttifaklar\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/Aliancas-Estrategicas.webp 200w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/Aliancas-Estrategicas-150x150.webp 150w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/Aliancas-Estrategicas-12x12.webp 12w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/Aliancas-Estrategicas-100x100.webp 100w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n<div class=\"row align-center\"  id=\"row-540428655\">\n\n\n\t<div id=\"col-301915440\" class=\"col medium-11 small-11 large-11\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h3><strong>Stratejik \u0130ttifaklar<\/strong><\/h3>\n<p>Novastar (MX40 kontrolc\u00fcler) ve Meanwell (LRS-200 g\u00fc\u00e7 kaynaklar\u0131) gibi devlerle ortakl\u0131klar. \u00dcst\u00fcn kaliteli bile\u015fenler, 97.3%&#039;nin \u00e7al\u0131\u015fma g\u00fcvenilirli\u011fini garanti eder.<\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-665687507 > .col-inner {\n  border-radius: 8px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1675475224\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner box-shadow-1\" style=\"background-color:rgb(255,255,255);\" >\n\t\t\t\n\t\t\t\n\n\t<div id=\"gap-1553567429\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1553567429 {\n  padding-top: 15px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 150px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/SMT.webp\" class=\"attachment-medium size-medium\" alt=\"SMT\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/SMT.webp 200w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/SMT-150x150.webp 150w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/SMT-12x12.webp 12w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/SMT-100x100.webp 100w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n<div class=\"row align-center\"  id=\"row-157573540\">\n\n\n\t<div id=\"col-1252805352\" class=\"col medium-11 small-11 large-11\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h3><strong>End\u00fcstriyel Alan<\/strong><\/h3>\n<p>5 GHz SMT hatlar\u0131 ve 56\u00b0C ESS odalar\u0131yla 30.000 m\u00b2 alan. G\u00fcnl\u00fck 15.000 mod\u00fcl \u00fcretim kapasitesi, ISO 9001 sertifikal\u0131 teknisyenler taraf\u0131ndan denetlenmektedir.<\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1675475224 > .col-inner {\n  border-radius: 8px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-822523444\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner box-shadow-1\" style=\"background-color:rgb(255,255,255);\" >\n\t\t\t\n\t\t\t\n\n\t<div id=\"gap-1783392986\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1783392986 {\n  padding-top: 15px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 150px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/Linguagem-Global.webp\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/Linguagem-Global.webp 200w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/Linguagem-Global-150x150.webp 150w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/Linguagem-Global-12x12.webp 12w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/Linguagem-Global-100x100.webp 100w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n<div class=\"row align-center\"  id=\"row-291953882\">\n\n\n\t<div id=\"col-2528924\" class=\"col medium-11 small-11 large-11\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h3><strong>K\u00fcresel Dil<\/strong><\/h3>\n<p>\u00c7ok dilli dok\u00fcmantasyon (Brezilya Portekizcesi dahil) ve IEC 62368-1 standard\u0131na uyumluluk. 7\/24 hizmet veren ekibimiz, h\u0131zland\u0131r\u0131lm\u0131\u015f sertifikasyon i\u00e7in ANATEL\/INMETRO standartlar\u0131nda uzmand\u0131r.<\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-822523444 > .col-inner {\n  border-radius: 8px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1696044844\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner box-shadow-1\" style=\"background-color:rgb(255,255,255);\" >\n\t\t\t\n\t\t\t\n\n\t<div id=\"gap-625508121\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-625508121 {\n  padding-top: 15px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 150px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/Experiencia-Comprovada.webp\" class=\"attachment-medium size-medium\" alt=\"Kan\u0131tlanm\u0131\u015f Deneyim\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/Experiencia-Comprovada.webp 200w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/Experiencia-Comprovada-150x150.webp 150w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/Experiencia-Comprovada-12x12.webp 12w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/Experiencia-Comprovada-100x100.webp 100w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n<div class=\"row align-center\"  id=\"row-561677657\">\n\n\n\t<div id=\"col-970729835\" class=\"col medium-11 small-11 large-11\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h3><strong>Kan\u0131tlanm\u0131\u015f Deneyim<\/strong><\/h3>\n<p>20 y\u0131ll\u0131k LED teknolojileri uzmanl\u0131\u011f\u0131: FIFA\u2122 stadyumlar\u0131 ve kongre merkezleri de dahil olmak \u00fczere 800&#039;den fazla kamu projesi tamamland\u0131. Karma\u015f\u0131k zorluklar i\u00e7in birle\u015ftirilmi\u015f bilgi birikimi.<\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1696044844 > .col-inner {\n  border-radius: 8px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n\t<\/div>\n\n\n\t<div id=\"gap-848856161\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-848856161 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<a href=\"#contact-form\" class=\"button primary\"  style=\"border-radius:99px;\">\n    <span>\u00dccretsiz fiyat teklifi<\/span>\n  <\/a>\n\n\n\t<div id=\"contact-form\"\n\t     class=\"lightbox-by-id lightbox-content mfp-hide lightbox-white\"\n\t     style=\"max-width:800px ;padding:30px\">\n\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f5-o30\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"5\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o30\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"\u0130leti\u015fim formu\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o30\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"5\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f5-o30\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class='custom_contact_style'>\n\t<p><label> Ad\u0131n\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-nome\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"name\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"seu-nome\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> E-postan\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"seu-email\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> Mesaj\u0131n\u0131z (iste\u011fe ba\u011fl\u0131)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"sua-mensagem\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"sua-mensagem\"><\/textarea><\/span> <\/label>\n\t<\/p>\n\t<div style=\"margin-bottom:10px;\">\n\t\t<p><span class=\"wpcf7-form-control-wrap kc_captcha cf7ic-toggle\" data-name=\"kc_captcha\"><span class=\"wpcf7-form-control wpcf7-radio\"><span class=\"captcha-image\" style=\"display: none;\"><span class=\"cf7ic_instructions\">L\u00fctfen se\u00e7erek insan oldu\u011funuzu kan\u0131tlay\u0131n.<span> bardak<\/span>.<\/span><label><input aria-label=\"1\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 576 512\"><path fill=\"currentColor\" d=\"M259 18l-65 132-146 22c-26 3-37 36-18 54l106 103-25 146c-5 26 23 46 46 33l131-68 131 68c23 13 51-7 46-33l-25-146 106-103c19-18 8-51-18-54l-146-22-65-132a32 32 0 00-58 0z\"\/><\/svg><\/label><label><input aria-label=\"2\" type=\"radio\" name=\"kc_captcha\" value=\"kc_human\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 640 512\"><path fill=\"currentColor\" d=\"M192 384h192c53 0 96-43 96-96h32a128 128 0 000-256H120c-13 0-24 11-24 24v232c0 53 43 96 96 96zM512 96a64 64 0 010 128h-32V96h32zm48 384H48c-47 0-61-64-36-64h584c25 0 11 64-36 64z\"\/><\/svg><\/label><label><input aria-label=\"3\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path fill=\"currentColor\" d=\"M512 176a176 176 0 01-209 173l-24 27a24 24 0 01-18 8h-37v40c0 13-11 24-24 24h-40v40c0 13-11 24-24 24H24c-13 0-24-11-24-24v-78c0-6 3-13 7-17l162-162a176 176 0 11343-55zm-176-48a48 48 0 1096 0 48 48 0 00-96 0z\"\/><\/svg><\/label>\r\n    <\/span>\r\n    <span style=\"display:none\">\r\n        <input type=\"text\" name=\"kc_honeypot\">\r\n    <\/span><\/span><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div style=\"width:100%;\">\n\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner full-width\" type=\"submit\" value=\"G\u00f6ndermek i\u00e7in\" \/>\n\t\t<\/p>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"tr\"\/><\/form>\n<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-928292795 > .col-inner {\n  margin: 0px 0px -30px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_426521954 {\n  padding-top: 40px;\n  padding-bottom: 40px;\n}\n@media (min-width:550px) {\n  #section_426521954 {\n    padding-top: 80px;\n    padding-bottom: 80px;\n  }\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section\" id=\"section_2069431973\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-width:1px 0px 0px 0px;\">\n\t<\/div>\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-432667785\">\n\n\n\t<div id=\"col-488950464\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-3095014027\" class=\"text\">\n\t\t\n\n<h2>Ba\u015far\u0131 Hikayeleri<\/h2>\n\t\t\n<style>\n#text-3095014027 {\n  font-size: 1rem;\n  line-height: 1.5;\n  text-align: center;\n}\n@media (min-width:850px) {\n  #text-3095014027 {\n    font-size: 1.2rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n  \n    <div class=\"row large-columns-3 medium-columns- small-columns-1\" >\n  <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/placa-de-publicidade-futebol-2.webp\" title=\"400 adet P10 Kabin LED Paneli D\u0131\u015f Mekan Futbol\">            <div class=\"box has-hover gallery-box box-shade dark\">\n              <div class=\"box-image image-zoom image-cover\" style=\"border-radius:3%;padding-top:75%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/placa-de-publicidade-futebol-2.webp\" class=\"attachment-original size-original\" alt=\"futbol-reklam-panosu\" ids=\"1806,1807,1809,1810,1811,1812,1814,1815,1816\" style=\"shade\" lightbox_image_size=\"original\" columns=\"3\" columns__sm=\"1\" image_height=\"75%\" image_radius=\"3\" image_size=\"original\" image_hover=\"zoom\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/placa-de-publicidade-futebol-2.webp 400w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/placa-de-publicidade-futebol-2-300x225.webp 300w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/placa-de-publicidade-futebol-2-16x12.webp 16w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                  <div class=\"shade\"><\/div>\n                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>400 adet P10 Kabin LED Paneli D\u0131\u015f Mekan Futbol<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/painel-de-led-perimetro.webp\" title=\"650 adet P10 \u00c7evre LED Paneli\">            <div class=\"box has-hover gallery-box box-shade dark\">\n              <div class=\"box-image image-zoom image-cover\" style=\"border-radius:3%;padding-top:75%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/painel-de-led-perimetro.webp\" class=\"attachment-original size-original\" alt=\"\u00e7evre-led-paneli\" ids=\"1806,1807,1809,1810,1811,1812,1814,1815,1816\" style=\"shade\" lightbox_image_size=\"original\" columns=\"3\" columns__sm=\"1\" image_height=\"75%\" image_radius=\"3\" image_size=\"original\" image_hover=\"zoom\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/painel-de-led-perimetro.webp 400w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/painel-de-led-perimetro-300x225.webp 300w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/painel-de-led-perimetro-16x12.webp 16w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                  <div class=\"shade\"><\/div>\n                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>650 adet P10 \u00c7evre LED Paneli<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/painel-de-led-para-propaganda-externa.webp\" title=\"D\u0131\u015f Mekan Reklamc\u0131l\u0131\u011f\u0131 i\u00e7in 60 m\u00b2 P10 LED Panel\">            <div class=\"box has-hover gallery-box box-shade dark\">\n              <div class=\"box-image image-zoom image-cover\" style=\"border-radius:3%;padding-top:75%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/painel-de-led-para-propaganda-externa.webp\" class=\"attachment-original size-original\" alt=\"D\u0131\u015f mekan reklamc\u0131l\u0131\u011f\u0131 i\u00e7in LED panel\" ids=\"1806,1807,1809,1810,1811,1812,1814,1815,1816\" style=\"shade\" lightbox_image_size=\"original\" columns=\"3\" columns__sm=\"1\" image_height=\"75%\" image_radius=\"3\" image_size=\"original\" image_hover=\"zoom\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/painel-de-led-para-propaganda-externa.webp 400w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/painel-de-led-para-propaganda-externa-300x225.webp 300w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/painel-de-led-para-propaganda-externa-16x12.webp 16w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                  <div class=\"shade\"><\/div>\n                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>D\u0131\u015f Mekan Reklamc\u0131l\u0131\u011f\u0131 i\u00e7in 60 m\u00b2 P10 LED Panel<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/tela-de-led-para-igreja.webp\" title=\"Kilise i\u00e7in 20 metrekarelik P5 LED Ekran\">            <div class=\"box has-hover gallery-box box-shade dark\">\n              <div class=\"box-image image-zoom image-cover\" style=\"border-radius:3%;padding-top:75%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/tela-de-led-para-igreja.webp\" class=\"attachment-original size-original\" alt=\"kilise i\u00e7in LED ekran\" ids=\"1806,1807,1809,1810,1811,1812,1814,1815,1816\" style=\"shade\" lightbox_image_size=\"original\" columns=\"3\" columns__sm=\"1\" image_height=\"75%\" image_radius=\"3\" image_size=\"original\" image_hover=\"zoom\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/tela-de-led-para-igreja.webp 400w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/tela-de-led-para-igreja-300x225.webp 300w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/tela-de-led-para-igreja-16x12.webp 16w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                  <div class=\"shade\"><\/div>\n                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Kilise i\u00e7in 20 metrekarelik P5 LED Ekran<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/telao-de-led-palco.webp\" title=\"42 metrekarelik P3.91 LED Sahne Perdesi\">            <div class=\"box has-hover gallery-box box-shade dark\">\n              <div class=\"box-image image-zoom image-cover\" style=\"border-radius:3%;padding-top:75%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/telao-de-led-palco.webp\" class=\"attachment-original size-original\" alt=\"LED sahne ekran\u0131\" ids=\"1806,1807,1809,1810,1811,1812,1814,1815,1816\" style=\"shade\" lightbox_image_size=\"original\" columns=\"3\" columns__sm=\"1\" image_height=\"75%\" image_radius=\"3\" image_size=\"original\" image_hover=\"zoom\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/telao-de-led-palco.webp 400w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/telao-de-led-palco-300x225.webp 300w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/telao-de-led-palco-16x12.webp 16w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                  <div class=\"shade\"><\/div>\n                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>42 metrekarelik P3.91 LED Sahne Perdesi<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/movable-led.webp\" title=\"55 metrekare P3.91 Kamyon \u00dczerinde Ta\u015f\u0131nabilir LED\">            <div class=\"box has-hover gallery-box box-shade dark\">\n              <div class=\"box-image image-zoom image-cover\" style=\"border-radius:3%;padding-top:75%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/movable-led.webp\" class=\"attachment-original size-original\" alt=\"hareketli LED\" ids=\"1806,1807,1809,1810,1811,1812,1814,1815,1816\" style=\"shade\" lightbox_image_size=\"original\" columns=\"3\" columns__sm=\"1\" image_height=\"75%\" image_radius=\"3\" image_size=\"original\" image_hover=\"zoom\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/movable-led.webp 400w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/movable-led-300x225.webp 300w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/movable-led-16x12.webp 16w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                  <div class=\"shade\"><\/div>\n                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>55 metrekare P3.91 Kamyon \u00dczerinde Ta\u015f\u0131nabilir LED<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/painel-de-led-para-piscina.webp\" title=\"12 m\u00b2 P2.5 LED Havuz Paneli\">            <div class=\"box has-hover gallery-box box-shade dark\">\n              <div class=\"box-image image-zoom image-cover\" style=\"border-radius:3%;padding-top:75%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/painel-de-led-para-piscina.webp\" class=\"attachment-original size-original\" alt=\"Y\u00fczme havuzu i\u00e7in LED panel\" ids=\"1806,1807,1809,1810,1811,1812,1814,1815,1816\" style=\"shade\" lightbox_image_size=\"original\" columns=\"3\" columns__sm=\"1\" image_height=\"75%\" image_radius=\"3\" image_size=\"original\" image_hover=\"zoom\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/painel-de-led-para-piscina.webp 400w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/painel-de-led-para-piscina-300x225.webp 300w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/painel-de-led-para-piscina-16x12.webp 16w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                  <div class=\"shade\"><\/div>\n                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>12 m\u00b2 P2.5 LED Havuz Paneli<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/piso-de-led.webp\" title=\"120 m\u00b2 P3.91 \u0130nteraktif LED Zemin\">            <div class=\"box has-hover gallery-box box-shade dark\">\n              <div class=\"box-image image-zoom image-cover\" style=\"border-radius:3%;padding-top:75%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/piso-de-led.webp\" class=\"attachment-original size-original\" alt=\"LED zemin\" ids=\"1806,1807,1809,1810,1811,1812,1814,1815,1816\" style=\"shade\" lightbox_image_size=\"original\" columns=\"3\" columns__sm=\"1\" image_height=\"75%\" image_radius=\"3\" image_size=\"original\" image_hover=\"zoom\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/piso-de-led.webp 400w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/piso-de-led-300x225.webp 300w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/piso-de-led-16x12.webp 16w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                  <div class=\"shade\"><\/div>\n                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>120 m\u00b2 P3.91 \u0130nteraktif LED Zemin<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/video-wall-led.webp\" title=\"500 metrekarelik P8 LED Video Duvar\u0131\">            <div class=\"box has-hover gallery-box box-shade dark\">\n              <div class=\"box-image image-zoom image-cover\" style=\"border-radius:3%;padding-top:75%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/video-wall-led.webp\" class=\"attachment-original size-original\" alt=\"LED video duvar\u0131\" ids=\"1806,1807,1809,1810,1811,1812,1814,1815,1816\" style=\"shade\" lightbox_image_size=\"original\" columns=\"3\" columns__sm=\"1\" image_height=\"75%\" image_radius=\"3\" image_size=\"original\" image_hover=\"zoom\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/video-wall-led.webp 400w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/video-wall-led-300x225.webp 300w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/video-wall-led-16x12.webp 16w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                  <div class=\"shade\"><\/div>\n                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>500 metrekarelik P8 LED Video Duvar\u0131<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><\/div>\n\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_2069431973 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  background-color: rgb(239, 248, 243);\n}\n@media (min-width:850px) {\n  #section_2069431973 {\n    padding-top: 60px;\n    padding-bottom: 60px;\n  }\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section\" id=\"section_1376429180\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n\t<div id=\"gap-824452185\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-824452185 {\n  padding-top: 40px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div id=\"text-3966369580\" class=\"text\">\n\t\t\n\n<h2>Orta\u011f\u0131m\u0131z<\/h2>\n\t\t\n<style>\n#text-3966369580 {\n  font-size: 1rem;\n  text-align: center;\n}\n@media (min-width:850px) {\n  #text-3966369580 {\n    font-size: 1.2rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-1373995843\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1373995843 {\n  padding-top: 15px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<div class=\"row\"  id=\"row-187259523\">\n\n\n\t<div id=\"col-1417959636\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"gap-1704069189\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1704069189 {\n  padding-top: 8px;\n}\n@media (min-width:850px) {\n  #gap-1704069189 {\n    padding-top: 30px;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\n\n  \n    <div class=\"row large-columns-7 medium-columns-3 small-columns-1 slider row-slider slider-nav-reveal slider-nav-push\"  data-flickity-options='{\"imagesLoaded\": true, \"groupCells\": \"100%\", \"dragThreshold\" : 5, \"cellAlign\": \"left\",\"wrapAround\": true,\"prevNextButtons\": true,\"percentPosition\": true,\"pageDots\": false, \"rightToLeft\": false, \"autoPlay\" : false}' >\n\n  <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-default\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"140\" height=\"70\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/epistar-led-chip-1.webp\" class=\"attachment-original size-original\" alt=\"Epistar LED \u00c7ipi\" ids=\"1818,1823,1820,1825,1817,1819,1824,1821,1822\" style=\"default\" lightbox=\"false\" type=\"slider\" columns=\"7\" columns__sm=\"1\" image_size=\"original\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/epistar-led-chip-1.webp 140w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/epistar-led-chip-1-18x9.webp 18w\" sizes=\"auto, (max-width: 140px) 100vw, 140px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-default\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"140\" height=\"70\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/nationstar.webp\" class=\"attachment-original size-original\" alt=\"ulus y\u0131ld\u0131z\u0131\" ids=\"1818,1823,1820,1825,1817,1819,1824,1821,1822\" style=\"default\" lightbox=\"false\" type=\"slider\" columns=\"7\" columns__sm=\"1\" image_size=\"original\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/nationstar.webp 140w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/nationstar-18x9.webp 18w\" sizes=\"auto, (max-width: 140px) 100vw, 140px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-default\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"140\" height=\"70\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/novastar.webp\" class=\"attachment-original size-original\" alt=\"novastar\" ids=\"1818,1823,1820,1825,1817,1819,1824,1821,1822\" style=\"default\" lightbox=\"false\" type=\"slider\" columns=\"7\" columns__sm=\"1\" image_size=\"original\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/novastar.webp 140w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/novastar-18x9.webp 18w\" sizes=\"auto, (max-width: 140px) 100vw, 140px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-default\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"140\" height=\"70\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/MEANWELL.webp\" class=\"attachment-original size-original\" alt=\"MEANWELL\" ids=\"1818,1823,1820,1825,1817,1819,1824,1821,1822\" style=\"default\" lightbox=\"false\" type=\"slider\" columns=\"7\" columns__sm=\"1\" image_size=\"original\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/MEANWELL.webp 140w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/MEANWELL-18x9.webp 18w\" sizes=\"auto, (max-width: 140px) 100vw, 140px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-default\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"140\" height=\"70\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/kystar-video-processor.webp\" class=\"attachment-original size-original\" alt=\"kystar-video-i\u015flemcisi\" ids=\"1818,1823,1820,1825,1817,1819,1824,1821,1822\" style=\"default\" lightbox=\"false\" type=\"slider\" columns=\"7\" columns__sm=\"1\" image_size=\"original\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/kystar-video-processor.webp 140w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/kystar-video-processor-18x9.webp 18w\" sizes=\"auto, (max-width: 140px) 100vw, 140px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-default\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"140\" height=\"70\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/huidu.webp\" class=\"attachment-original size-original\" alt=\"huidu\" ids=\"1818,1823,1820,1825,1817,1819,1824,1821,1822\" style=\"default\" lightbox=\"false\" type=\"slider\" columns=\"7\" columns__sm=\"1\" image_size=\"original\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/huidu.webp 140w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/huidu-18x9.webp 18w\" sizes=\"auto, (max-width: 140px) 100vw, 140px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-default\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"140\" height=\"70\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/LINSN.webp\" class=\"attachment-original size-original\" alt=\"LINSN\" ids=\"1818,1823,1820,1825,1817,1819,1824,1821,1822\" style=\"default\" lightbox=\"false\" type=\"slider\" columns=\"7\" columns__sm=\"1\" image_size=\"original\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/LINSN.webp 140w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/LINSN-18x9.webp 18w\" sizes=\"auto, (max-width: 140px) 100vw, 140px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-default\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"140\" height=\"70\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/VDwall.webp\" class=\"attachment-original size-original\" alt=\"VDwall\" ids=\"1818,1823,1820,1825,1817,1819,1824,1821,1822\" style=\"default\" lightbox=\"false\" type=\"slider\" columns=\"7\" columns__sm=\"1\" image_size=\"original\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/VDwall.webp 140w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/VDwall-18x9.webp 18w\" sizes=\"auto, (max-width: 140px) 100vw, 140px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-default\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"140\" height=\"70\" src=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/rgblink.webp\" class=\"attachment-original size-original\" alt=\"rgblink\" ids=\"1818,1823,1820,1825,1817,1819,1824,1821,1822\" style=\"default\" lightbox=\"false\" type=\"slider\" columns=\"7\" columns__sm=\"1\" image_size=\"original\" srcset=\"https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/rgblink.webp 140w, https:\/\/www.telaled.com\/wp-content\/uploads\/2025\/05\/rgblink-18x9.webp 18w\" sizes=\"auto, (max-width: 140px) 100vw, 140px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1376429180 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n@media (min-width:550px) {\n  #section_1376429180 {\n    padding-top: 30px;\n    padding-bottom: 30px;\n  }\n}\n@media (min-width:850px) {\n  #section_1376429180 {\n    padding-top: 50px;\n    padding-bottom: 50px;\n  }\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section\" id=\"section_1477719353\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n\t<div id=\"gap-1521744262\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1521744262 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div id=\"text-3019107274\" class=\"text\">\n\t\t\n\n<h2>M\u00fckemmel LED \u00e7\u00f6z\u00fcm\u00fcne haz\u0131r m\u0131s\u0131n\u0131z? \u2728<\/h2>\n<h2>Bizimle ileti\u015fime ge\u00e7in ve \u00fccretsiz dan\u0131\u015fmanl\u0131k hizmetimizden yararlan\u0131n!<\/h2>\n\t\t\n<style>\n#text-3019107274 {\n  text-align: center;\n  color: rgb(255,255,255);\n}\n#text-3019107274 > * {\n  color: rgb(255,255,255);\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"text-center\"><div class=\"is-divider divider clearfix\" style=\"background-color:rgb(254, 252, 252);\"><\/div><\/div>\n\n<div class=\"row align-center\"  id=\"row-1759699490\">\n\n\n\t<div id=\"col-1611674430\" class=\"col medium-5 small-12 large-5\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n<a href=\"#contact-form\" class=\"button white\"  style=\"border-radius:99px;\">\n    <span>Daha fazla bilgi edin<\/span>\n  <i class=\"icon-angle-right\" aria-hidden=\"true\" ><\/i><\/a>\n\n\n\t<div id=\"contact-form\"\n\t     class=\"lightbox-by-id lightbox-content mfp-hide lightbox-white\"\n\t     style=\"max-width:800px ;padding:30px\">\n\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f5-o31\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"5\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o31\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"\u0130leti\u015fim formu\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f5-o31\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"5\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f5-o31\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class='custom_contact_style'>\n\t<p><label> Ad\u0131n\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-nome\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"name\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"seu-nome\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> E-postan\u0131z<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"seu-email\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> Mesaj\u0131n\u0131z (iste\u011fe ba\u011fl\u0131)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"sua-mensagem\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"sua-mensagem\"><\/textarea><\/span> <\/label>\n\t<\/p>\n\t<div style=\"margin-bottom:10px;\">\n\t\t<p><span class=\"wpcf7-form-control-wrap kc_captcha cf7ic-toggle\" data-name=\"kc_captcha\"><span class=\"wpcf7-form-control wpcf7-radio\"><span class=\"captcha-image\" style=\"display: none;\"><span class=\"cf7ic_instructions\">L\u00fctfen se\u00e7erek insan oldu\u011funuzu kan\u0131tlay\u0131n.<span> bardak<\/span>.<\/span><label><input aria-label=\"1\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path fill=\"currentColor\" d=\"M500 168h-55l-8-21a127 127 0 00-120-83H195a127 127 0 00-120 83l-8 21H12c-8 0-14 8-11 16l8 24a12 12 0 0011 8h29a64 64 0 00-33 56v48c0 16 6 31 16 42v62c0 13 11 24 24 24h48c13 0 24-11 24-24v-40h256v40c0 13 11 24 24 24h48c13 0 24-11 24-24v-62c10-11 16-26 16-42v-48c0-24-13-45-33-56h29a12 12 0 0011-8l8-24c3-8-3-16-11-16zm-365 2c9-25 33-42 60-42h122c27 0 51 17 60 42l15 38H120l15-38zM88 328a32 32 0 010-64c18 0 48 30 48 48s-30 16-48 16zm336 0c-18 0-48 2-48-16s30-48 48-48 32 14 32 32-14 32-32 32z\"\/><\/svg><\/label><label><input aria-label=\"2\" type=\"radio\" name=\"kc_captcha\" value=\"kc_human\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 640 512\"><path fill=\"currentColor\" d=\"M192 384h192c53 0 96-43 96-96h32a128 128 0 000-256H120c-13 0-24 11-24 24v232c0 53 43 96 96 96zM512 96a64 64 0 010 128h-32V96h32zm48 384H48c-47 0-61-64-36-64h584c25 0 11 64-36 64z\"\/><\/svg><\/label><label><input aria-label=\"3\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path fill=\"currentColor\" d=\"M350 99c-54 0-98-35-166-35-25 0-47 4-68 12a56 56 0 004-24C118 24 95 1 66 0a56 56 0 00-34 102v386c0 13 11 24 24 24h16c13 0 24-11 24-24v-94c28-12 64-23 114-23 54 0 98 35 166 35 48 0 86-16 122-41 9-6 14-15 14-26V96c0-23-24-39-45-29-35 16-77 32-117 32z\"\/><\/svg><\/label>\r\n    <\/span>\r\n    <span style=\"display:none\">\r\n        <input type=\"text\" name=\"kc_honeypot\">\r\n    <\/span><\/span><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div style=\"width:100%;\">\n\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner full-width\" type=\"submit\" value=\"G\u00f6ndermek i\u00e7in\" \/>\n\t\t<\/p>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"tr\"\/><\/form>\n<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1477719353 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  background-color: rgb(0, 151, 57);\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section\" id=\"section_560669156\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-width:0px 0px 0px 0px;margin:0px 0px 0px 0px;\">\n\t<\/div>\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-332975684\">\n\n\n\t<div id=\"col-700610792\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"gap-1717868736\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1717868736 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div id=\"text-357659529\" class=\"text\">\n\t\t\n\n<h2>\u00c7\u00f6z\u00fcm\u00fcn\u00fcz\u00fc \u015fimdi al\u0131n!<\/h2>\n\t\t\n<style>\n#text-357659529 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-1120825392\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1120825392 {\n  padding-top: 20px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f2073-o32\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"2073\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f2073-o32\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"\u0130leti\u015fim formu\" enctype=\"multipart\/form-data\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/tr\/wp-json\/wp\/v2\/pages\/1684#wpcf7-f2073-o32\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"2073\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f2073-o32\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"telaled-uniform-form\">\n <!-- \u7b2c\u4e00\u884c - \u7edf\u4e00\u9ad8\u5ea6 -->\n\t<div class=\"form-row uniform-row\">\n\t\t<div class=\"form-col\">\n\t\t\t<p><label>Hangi t\u00fcr\u00fcne ihtiyac\u0131n\u0131z olacak?<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"tipo-desejado\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required uniform-field\" aria-required=\"true\" aria-invalid=\"false\" name=\"tipo-desejado\"><option value=\"Midia Outdoor\">A\u00e7\u0131k Hava Medyas\u0131<\/option><option value=\"Midia Indoor\">\u0130\u00e7 Mekan Medya<\/option><\/select><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"form-col\">\n\t\t\t<p><label>PROJE DURUMU<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"status-projeto\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required uniform-field\" aria-required=\"true\" aria-invalid=\"false\" name=\"status-projeto\"><option value=\"Comparando o custo, pronto para comprar\">Maliyetleri kar\u015f\u0131la\u015ft\u0131rd\u0131m, sat\u0131n almaya haz\u0131r\u0131m.<\/option><option value=\"Precisa instalar em at\u00e9 6 meses\">Kurulumun 6 ay i\u00e7inde tamamlanmas\u0131 gerekmektedir.<\/option><option value=\"Ainda confirme as informa\u00e7\u00f5es para escolher o produto correto\">L\u00fctfen do\u011fru \u00fcr\u00fcn\u00fc se\u00e7meden \u00f6nce bilgileri teyit edin.<\/option><option value=\"S\u00f3 estou interessado, sem projeto no momento\">Sadece ilgileniyorum, \u015fu anda bir projem yok.<\/option><\/select><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\n <!-- \u7b2c\u4e8c\u884c - \u7edf\u4e00\u9ad8\u5ea6 -->\n\t<div class=\"form-row uniform-row\">\n\t\t<div class=\"form-col\">\n\t\t\t<p><label>KURULUM<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"tipo-instalacao\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required uniform-field\" aria-required=\"true\" aria-invalid=\"false\" name=\"tipo-instalacao\"><option value=\"Fixo\">Sabit<\/option><option value=\"M\u00f3vel\">Mobil<\/option><\/select><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"form-col\">\n\t\t\t<p><label>G\u00d6R\u00dc\u015e MESAFES\u0130 (metre)<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"distancia\"><input class=\"wpcf7-form-control wpcf7-number wpcf7-validates-as-number uniform-field\" min=\"0\" step=\"0.01\" aria-invalid=\"false\" value=\"\" type=\"number\" name=\"distancia\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\n <!-- \u7b2c\u4e09\u884c -->\n\t<div class=\"form-row uniform-row\">\n\t\t<div class=\"form-col\">\n\t\t\t<p><label>GEN\u0130\u015eL\u0130K (metre)<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"largura\"><input class=\"wpcf7-form-control wpcf7-number wpcf7-validates-as-number uniform-field\" min=\"0.1\" step=\"0.01\" aria-invalid=\"false\" value=\"\" type=\"number\" name=\"largura\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"form-col\">\n\t\t\t<p><label>Y\u00dcKSEKL\u0130K (metre)<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"altura\"><input class=\"wpcf7-form-control wpcf7-number wpcf7-validates-as-number uniform-field\" min=\"0.1\" step=\"0.01\" aria-invalid=\"false\" value=\"\" type=\"number\" name=\"altura\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\n <!-- \u7b2c\u56db\u884c -->\n\t<div class=\"form-row uniform-row\">\n\t\t<div class=\"form-col\">\n\t\t\t<p><label>AD SOYAD *<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"nome-completo\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required uniform-field\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"nome-completo\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"form-col\">\n\t\t\t<p><label>E-POSTA *<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"seu-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email uniform-field\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"seu-email\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\n <!-- \u7b2c\u4e94\u884c - \u5168\u5bbd\u6587\u672c\u57df -->\n\t<div class=\"form-full-row\">\n\t\t<p><label>MESAJ<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"mensagem\"><textarea cols=\"40\" rows=\"4\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea uniform-textarea\" aria-invalid=\"false\" name=\"mensagem\"><\/textarea><\/span>\n\t\t<\/p>\n\t<\/div>\n\n <!-- \u7b2c\u516d\u884c -->\n\t<div class=\"form-full-row\">\n\t\t<p><label>DOSYA Y\u00dcKLEME (\u0130STE\u011eE BA\u011eLI)<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"upload-arquivo\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-file\" accept=\".jpg,.png,.pdf,.doc,.docx,.zip\" aria-invalid=\"false\" type=\"file\" name=\"upload-arquivo\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div style=\"margin-bottom:10px; style=\"width:100%\">\n\t\t<p><span class=\"wpcf7-form-control-wrap kc_captcha cf7ic-toggle\" data-name=\"kc_captcha\"><span class=\"wpcf7-form-control wpcf7-radio\"><span class=\"captcha-image\" style=\"display: none;\"><span class=\"cf7ic_instructions\">L\u00fctfen se\u00e7erek insan oldu\u011funuzu kan\u0131tlay\u0131n.<span> y\u0131ld\u0131z<\/span>.<\/span><label><input aria-label=\"1\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 576 512\"><path fill=\"currentColor\" d=\"M488 313v143c0 13-11 24-24 24H348c-7 0-12-5-12-12V356c0-7-5-12-12-12h-72c-7 0-12 5-12 12v112c0 7-5 12-12 12H112c-13 0-24-11-24-24V313c0-4 2-7 4-10l188-154c5-4 11-4 16 0l188 154c2 3 4 6 4 10zm84-61l-84-69V44c0-6-5-12-12-12h-56c-7 0-12 6-12 12v73l-89-74a48 48 0 00-61 0L4 252c-5 4-5 12-1 17l25 31c5 5 12 5 17 1l235-193c5-4 11-4 16 0l235 193c5 5 13 4 17-1l25-31c4-6 4-13-1-17z\"\/><\/svg><\/label><label><input aria-label=\"2\" type=\"radio\" name=\"kc_captcha\" value=\"kc_human\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 576 512\"><path fill=\"currentColor\" d=\"M259 18l-65 132-146 22c-26 3-37 36-18 54l106 103-25 146c-5 26 23 46 46 33l131-68 131 68c23 13 51-7 46-33l-25-146 106-103c19-18 8-51-18-54l-146-22-65-132a32 32 0 00-58 0z\"\/><\/svg><\/label><label><input aria-label=\"3\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path fill=\"currentColor\" d=\"M512 176a176 176 0 01-209 173l-24 27a24 24 0 01-18 8h-37v40c0 13-11 24-24 24h-40v40c0 13-11 24-24 24H24c-13 0-24-11-24-24v-78c0-6 3-13 7-17l162-162a176 176 0 11343-55zm-176-48a48 48 0 1096 0 48 48 0 00-96 0z\"\/><\/svg><\/label>\r\n    <\/span>\r\n    <span style=\"display:none\">\r\n        <input type=\"text\" name=\"kc_honeypot\">\r\n    <\/span><\/span><\/span>\n\t\t<\/p>\n\t<\/div>\n\n <!-- \u63d0\u4ea4\u6309\u94ae -->\n\t<div class=\"form-submit-row\">\n\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner uniform-submit\" type=\"submit\" value=\"MESAJ G\u00d6NDER\" \/>\n\t\t<\/p>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"tr\"\/><\/form>\n<\/div>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\n<style>\n#row-332975684 > .col > .col-inner {\n  padding: 0px 50px 0px 50px;\n}\n<\/style>\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_560669156 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"footnotes":""},"class_list":["post-1684","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Especialista em Display LED e LCD: Solu\u00e7\u00f5es Comerciais - TELALED<\/title>\n<meta name=\"description\" content=\"Fornecedor l\u00edder de pain\u00e9is LED publicit\u00e1rios e displays LCD comerciais. Solicite or\u00e7amento gr\u00e1tis para sua solu\u00e7\u00e3o em visualiza\u00e7\u00e3o digital!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.telaled.com\/tr\/\" \/>\n<meta property=\"og:locale\" content=\"tr_TR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Especialista em Display LED e LCD: Solu\u00e7\u00f5es Comerciais - TELALED\" \/>\n<meta property=\"og:description\" content=\"Fornecedor l\u00edder de pain\u00e9is LED publicit\u00e1rios e displays LCD comerciais. Solicite or\u00e7amento gr\u00e1tis para sua solu\u00e7\u00e3o em visualiza\u00e7\u00e3o digital!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.telaled.com\/tr\/\" \/>\n<meta property=\"og:site_name\" content=\"TELALED\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-15T11:42:14+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tahmini okuma s\u00fcresi\" \/>\n\t<meta name=\"twitter:data1\" content=\"21 dakika\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.telaled.com\\\/\",\"url\":\"https:\\\/\\\/www.telaled.com\\\/\",\"name\":\"Especialista em Display LED e LCD: Solu\u00e7\u00f5es Comerciais - TELALED\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.telaled.com\\\/#website\"},\"datePublished\":\"2025-04-23T11:38:58+00:00\",\"dateModified\":\"2025-07-15T11:42:14+00:00\",\"description\":\"Fornecedor l\u00edder de pain\u00e9is LED publicit\u00e1rios e displays LCD comerciais. Solicite or\u00e7amento gr\u00e1tis para sua solu\u00e7\u00e3o em visualiza\u00e7\u00e3o digital!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.telaled.com\\\/#breadcrumb\"},\"inLanguage\":\"tr\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.telaled.com\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.telaled.com\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.telaled.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"HOME\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.telaled.com\\\/#website\",\"url\":\"https:\\\/\\\/www.telaled.com\\\/\",\"name\":\"TELALED\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.telaled.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"tr\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LED ve LCD Ekranlar Uzman\u0131: Ticari \u00c7\u00f6z\u00fcmler - TELALED","description":"LED reklam panelleri ve ticari LCD ekranlar\u0131n \u00f6nde gelen tedarik\u00e7isi. Dijital g\u00f6rselle\u015ftirme \u00e7\u00f6z\u00fcm\u00fcn\u00fcz i\u00e7in \u00fccretsiz fiyat teklifi isteyin!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.telaled.com\/tr\/","og_locale":"tr_TR","og_type":"article","og_title":"Especialista em Display LED e LCD: Solu\u00e7\u00f5es Comerciais - TELALED","og_description":"Fornecedor l\u00edder de pain\u00e9is LED publicit\u00e1rios e displays LCD comerciais. Solicite or\u00e7amento gr\u00e1tis para sua solu\u00e7\u00e3o em visualiza\u00e7\u00e3o digital!","og_url":"https:\/\/www.telaled.com\/tr\/","og_site_name":"TELALED","article_modified_time":"2025-07-15T11:42:14+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tahmini okuma s\u00fcresi":"21 dakika"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.telaled.com\/","url":"https:\/\/www.telaled.com\/","name":"LED ve LCD Ekranlar Uzman\u0131: Ticari \u00c7\u00f6z\u00fcmler - TELALED","isPartOf":{"@id":"https:\/\/www.telaled.com\/#website"},"datePublished":"2025-04-23T11:38:58+00:00","dateModified":"2025-07-15T11:42:14+00:00","description":"LED reklam panelleri ve ticari LCD ekranlar\u0131n \u00f6nde gelen tedarik\u00e7isi. Dijital g\u00f6rselle\u015ftirme \u00e7\u00f6z\u00fcm\u00fcn\u00fcz i\u00e7in \u00fccretsiz fiyat teklifi isteyin!","breadcrumb":{"@id":"https:\/\/www.telaled.com\/#breadcrumb"},"inLanguage":"tr","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.telaled.com\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.telaled.com\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.telaled.com\/"},{"@type":"ListItem","position":2,"name":"HOME"}]},{"@type":"WebSite","@id":"https:\/\/www.telaled.com\/#website","url":"https:\/\/www.telaled.com\/","name":"LED Ekran","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.telaled.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"tr"}]}},"_links":{"self":[{"href":"https:\/\/www.telaled.com\/tr\/wp-json\/wp\/v2\/pages\/1684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.telaled.com\/tr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.telaled.com\/tr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.telaled.com\/tr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.telaled.com\/tr\/wp-json\/wp\/v2\/comments?post=1684"}],"version-history":[{"count":79,"href":"https:\/\/www.telaled.com\/tr\/wp-json\/wp\/v2\/pages\/1684\/revisions"}],"predecessor-version":[{"id":2564,"href":"https:\/\/www.telaled.com\/tr\/wp-json\/wp\/v2\/pages\/1684\/revisions\/2564"}],"wp:attachment":[{"href":"https:\/\/www.telaled.com\/tr\/wp-json\/wp\/v2\/media?parent=1684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}